{"id":5866,"date":"2022-01-20T15:22:15","date_gmt":"2022-01-20T14:22:15","guid":{"rendered":"http:\/\/164.90.193.213\/?post_type=prodotti&#038;p=5866"},"modified":"2023-12-01T13:50:57","modified_gmt":"2023-12-01T12:50:57","slug":"barometro-digitale-di-precisione-bar-av","status":"publish","type":"prodotti","link":"https:\/\/nesasrl.sp2.netkom.it\/it\/prodotti\/barometro-digitale-di-precisione-bar-av\/","title":{"rendered":"Barometro digitale ad alta precisione"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>BAR-AV<\/p>\n","protected":false},"featured_media":5869,"template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categoria_prodotti":[55],"class_list":["post-5866","prodotti","type-prodotti","status-publish","has-post-thumbnail","hentry","categoria_prodotti-pressione"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Barometro digitale ad alta precisione - Pressione - Nesa<\/title>\n<meta name=\"description\" content=\"Il Barometro digitale BAR-AV \u00e8 uno strumento elettronico di alta precisione per misure di pressione assoluta, QNH, QFE, QFF. L\u2019eccellente stabilit\u00e0 a lungo termine e l\u2019interfaccia web, ne fanno un dispositivo ideale per applicazioni in meteorologia professionale, sistemi aeroportuali e di monitoraggio industriale. Un robusto contenitore IP67 permette una facile installazione anche in condizioni ambientali gravose. Disponibile nella versione a singolo sensore o con 3 sensori per una maggiore precisione estesa\u00a0 (modello BAR-AV-S) \u00c8 realizzato in conformit\u00e0 agli standard WMO \u2013 ICAO.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/barometro-digitale-di-precisione-bar-av\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barometro digitale ad alta precisione - Pressione - Nesa\" \/>\n<meta property=\"og:description\" content=\"Il Barometro digitale BAR-AV \u00e8 uno strumento elettronico di alta precisione per misure di pressione assoluta, QNH, QFE, QFF. L\u2019eccellente stabilit\u00e0 a lungo termine e l\u2019interfaccia web, ne fanno un dispositivo ideale per applicazioni in meteorologia professionale, sistemi aeroportuali e di monitoraggio industriale. Un robusto contenitore IP67 permette una facile installazione anche in condizioni ambientali gravose. Disponibile nella versione a singolo sensore o con 3 sensori per una maggiore precisione estesa\u00a0 (modello BAR-AV-S) \u00c8 realizzato in conformit\u00e0 agli standard WMO \u2013 ICAO.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/barometro-digitale-di-precisione-bar-av\/\" \/>\n<meta property=\"og:site_name\" content=\"Nesa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nesasrl\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-01T12:50:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2022\/01\/strumenti-sensori-pressione-BAR-Av.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/barometro-digitale-di-precisione-bar-av\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/barometro-digitale-di-precisione-bar-av\/\",\"name\":\"Barometro digitale ad alta precisione - Pressione - Nesa\",\"isPartOf\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\"},\"datePublished\":\"2022-01-20T14:22:15+00:00\",\"dateModified\":\"2023-12-01T12:50:57+00:00\",\"description\":\"Il Barometro digitale BAR-AV \u00e8 uno strumento elettronico di alta precisione per misure di pressione assoluta, QNH, QFE, QFF. L\u2019eccellente stabilit\u00e0 a lungo termine e l\u2019interfaccia web, ne fanno un dispositivo ideale per applicazioni in meteorologia professionale, sistemi aeroportuali e di monitoraggio industriale. Un robusto contenitore IP67 permette una facile installazione anche in condizioni ambientali gravose. Disponibile nella versione a singolo sensore o con 3 sensori per una maggiore precisione estesa\u00a0 (modello BAR-AV-S) \u00c8 realizzato in conformit\u00e0 agli standard WMO \u2013 ICAO.\",\"breadcrumb\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/barometro-digitale-di-precisione-bar-av\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/barometro-digitale-di-precisione-bar-av\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/barometro-digitale-di-precisione-bar-av\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/strumenti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sensori\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/sensori\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Pressione\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/pressione\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Barometro digitale ad alta precisione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"name\":\"Nesa\",\"description\":\"Sistemi per il monitoraggio ambientale e telecontrollo\",\"publisher\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\",\"name\":\"Nesa srl\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"contentUrl\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"width\":264,\"height\":55,\"caption\":\"Nesa srl\"},\"image\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/nesa-srl\/\",\"https:\/\/www.facebook.com\/nesasrl\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Barometro digitale ad alta precisione - Pressione - Nesa","description":"Il Barometro digitale BAR-AV \u00e8 uno strumento elettronico di alta precisione per misure di pressione assoluta, QNH, QFE, QFF. L\u2019eccellente stabilit\u00e0 a lungo termine e l\u2019interfaccia web, ne fanno un dispositivo ideale per applicazioni in meteorologia professionale, sistemi aeroportuali e di monitoraggio industriale. Un robusto contenitore IP67 permette una facile installazione anche in condizioni ambientali gravose. Disponibile nella versione a singolo sensore o con 3 sensori per una maggiore precisione estesa\u00a0 (modello BAR-AV-S) \u00c8 realizzato in conformit\u00e0 agli standard WMO \u2013 ICAO.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/barometro-digitale-di-precisione-bar-av\/","og_locale":"en_US","og_type":"article","og_title":"Barometro digitale ad alta precisione - Pressione - Nesa","og_description":"Il Barometro digitale BAR-AV \u00e8 uno strumento elettronico di alta precisione per misure di pressione assoluta, QNH, QFE, QFF. L\u2019eccellente stabilit\u00e0 a lungo termine e l\u2019interfaccia web, ne fanno un dispositivo ideale per applicazioni in meteorologia professionale, sistemi aeroportuali e di monitoraggio industriale. Un robusto contenitore IP67 permette una facile installazione anche in condizioni ambientali gravose. Disponibile nella versione a singolo sensore o con 3 sensori per una maggiore precisione estesa\u00a0 (modello BAR-AV-S) \u00c8 realizzato in conformit\u00e0 agli standard WMO \u2013 ICAO.","og_url":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/barometro-digitale-di-precisione-bar-av\/","og_site_name":"Nesa","article_publisher":"https:\/\/www.facebook.com\/nesasrl","article_modified_time":"2023-12-01T12:50:57+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2022\/01\/strumenti-sensori-pressione-BAR-Av.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/barometro-digitale-di-precisione-bar-av\/","url":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/barometro-digitale-di-precisione-bar-av\/","name":"Barometro digitale ad alta precisione - Pressione - Nesa","isPartOf":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#website"},"datePublished":"2022-01-20T14:22:15+00:00","dateModified":"2023-12-01T12:50:57+00:00","description":"Il Barometro digitale BAR-AV \u00e8 uno strumento elettronico di alta precisione per misure di pressione assoluta, QNH, QFE, QFF. L\u2019eccellente stabilit\u00e0 a lungo termine e l\u2019interfaccia web, ne fanno un dispositivo ideale per applicazioni in meteorologia professionale, sistemi aeroportuali e di monitoraggio industriale. Un robusto contenitore IP67 permette una facile installazione anche in condizioni ambientali gravose. Disponibile nella versione a singolo sensore o con 3 sensori per una maggiore precisione estesa\u00a0 (modello BAR-AV-S) \u00c8 realizzato in conformit\u00e0 agli standard WMO \u2013 ICAO.","breadcrumb":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/barometro-digitale-di-precisione-bar-av\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nesasrl.sp2.netkom.it\/prodotti\/barometro-digitale-di-precisione-bar-av\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/barometro-digitale-di-precisione-bar-av\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nesasrl.sp2.netkom.it\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/strumenti\/"},{"@type":"ListItem","position":3,"name":"Sensori","item":"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/sensori\/"},{"@type":"ListItem","position":4,"name":"Pressione","item":"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/pressione\/"},{"@type":"ListItem","position":5,"name":"Barometro digitale ad alta precisione"}]},{"@type":"WebSite","@id":"https:\/\/nesasrl.sp2.netkom.it\/#website","url":"https:\/\/nesasrl.sp2.netkom.it\/","name":"Nesa","description":"Sistemi per il monitoraggio ambientale e telecontrollo","publisher":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization","name":"Nesa srl","url":"https:\/\/nesasrl.sp2.netkom.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/","url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","contentUrl":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","width":264,"height":55,"caption":"Nesa srl"},"image":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/nesa-srl\/","https:\/\/www.facebook.com\/nesasrl"]}]}},"_links":{"self":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/prodotti\/5866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/prodotti"}],"about":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/types\/prodotti"}],"version-history":[{"count":26,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/prodotti\/5866\/revisions"}],"predecessor-version":[{"id":23792,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/prodotti\/5866\/revisions\/23792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/media\/5869"}],"wp:attachment":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/media?parent=5866"}],"wp:term":[{"taxonomy":"categoria_prodotti","embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/categoria_prodotti?post=5866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}