{"id":5778,"date":"2022-01-20T14:23:03","date_gmt":"2022-01-20T13:23:03","guid":{"rendered":"http:\/\/164.90.193.213\/?post_type=prodotti&#038;p=5778"},"modified":"2022-12-17T17:15:01","modified_gmt":"2022-12-17T16:15:01","slug":"disdrometro-radar-tipologia-e-intensita-precipitazioni-dis","status":"publish","type":"prodotti","link":"https:\/\/nesasrl.sp2.netkom.it\/it\/prodotti\/disdrometro-radar-tipologia-e-intensita-precipitazioni-dis\/","title":{"rendered":"Disdrometro tipologia e intensit\u00e0 precipitazioni"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5778\" class=\"elementor elementor-5778\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b91e515 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b91e515\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2b7fcc0\" data-id=\"2b7fcc0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3db4bf5 elementor-widget elementor-widget-text-editor\" data-id=\"3db4bf5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Accessori correlati<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bd56de elementor-widget elementor-widget-heading\" data-id=\"0bd56de\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h3 class=\"elementor-heading-title elementor-size-default\">Questo sensore impiega alcuni dei nostri accessori<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-08594d6\" data-id=\"08594d6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83ac06f elementor--h-position-left elementor-arrows-position-outside elementor--v-position-bottom slider-nesa elementor-widget elementor-widget-slides\" data-id=\"83ac06f\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;arrows&quot;,&quot;transition_speed&quot;:300,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.7.2 - 15-06-2022 *\/\n.elementor-slides .swiper-slide-bg{background-size:cover;background-position:50%;background-repeat:no-repeat;min-width:100%;min-height:100%}.elementor-slides .swiper-slide-inner{background-repeat:no-repeat;background-position:50%;position:absolute;top:0;left:0;bottom:0;right:0;padding:50px;margin:auto}.elementor-slides .swiper-slide-inner,.elementor-slides .swiper-slide-inner:hover{color:#fff;display:-webkit-box;display:-ms-flexbox;display:flex}.elementor-slides .swiper-slide-inner .elementor-background-overlay{position:absolute;z-index:0;top:0;bottom:0;left:0;right:0}.elementor-slides .swiper-slide-inner .elementor-slide-content{position:relative;z-index:1;width:100%}.elementor-slides .swiper-slide-inner .elementor-slide-heading{font-size:35px;font-weight:700;line-height:1}.elementor-slides .swiper-slide-inner .elementor-slide-description{font-size:17px;line-height:1.4}.elementor-slides .swiper-slide-inner .elementor-slide-description:not(:last-child),.elementor-slides .swiper-slide-inner .elementor-slide-heading:not(:last-child){margin-bottom:30px}.elementor-slides .swiper-slide-inner .elementor-slide-button{border:2px solid #fff;color:#fff;background:transparent;display:inline-block}.elementor-slides .swiper-slide-inner .elementor-slide-button,.elementor-slides .swiper-slide-inner .elementor-slide-button:hover{background:transparent;color:inherit;text-decoration:none}.elementor--v-position-top .swiper-slide-inner{-webkit-box-align:start;-ms-flex-align:start;align-items:flex-start}.elementor--v-position-bottom .swiper-slide-inner{-webkit-box-align:end;-ms-flex-align:end;align-items:flex-end}.elementor--v-position-middle .swiper-slide-inner{-webkit-box-align:center;-ms-flex-align:center;align-items:center}.elementor--h-position-left .swiper-slide-inner{-webkit-box-pack:start;-ms-flex-pack:start;justify-content:flex-start}.elementor--h-position-right .swiper-slide-inner{-webkit-box-pack:end;-ms-flex-pack:end;justify-content:flex-end}.elementor--h-position-center .swiper-slide-inner{-webkit-box-pack:center;-ms-flex-pack:center;justify-content:center}body.rtl .elementor-widget-slides .elementor-swiper-button-next{left:10px;right:auto}body.rtl .elementor-widget-slides .elementor-swiper-button-prev{right:10px;left:auto}.elementor-slides-wrapper div:not(.swiper-slide)>.swiper-slide-inner{display:none}@media (max-width:767px){.elementor-slides .swiper-slide-inner{padding:30px}.elementor-slides .swiper-slide-inner .elementor-slide-heading{font-size:23px;line-height:1;margin-bottom:15px}.elementor-slides .swiper-slide-inner .elementor-slide-description{font-size:13px;line-height:1.4;margin-bottom:15px}}<\/style>\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper-container\" dir=\"ltr\" data-animation=\"fadeInRight\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-ba2c74b swiper-slide\"><div class=\"swiper-slide-bg\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/cavo-sensore\/\"><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Accessori - Cavo sensore<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-0782875 swiper-slide\"><div class=\"swiper-slide-bg\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/supporto-universale-per-sensori-standard-ssu\/\"><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Supporto universale - SSU<\/div><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>DIS<\/p>\n","protected":false},"featured_media":8903,"template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categoria_prodotti":[53],"class_list":["post-5778","prodotti","type-prodotti","status-publish","has-post-thumbnail","hentry","categoria_prodotti-monitoraggio-strade"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Disdrometro tipologia e intensit\u00e0 precipitazioni - Monitoraggio strade - Nesa<\/title>\n<meta name=\"description\" content=\"Sensore elettronico professionale della famiglia WSxxx basato su tecnologia radar doppler a 24Ghz, in grado di determinare la precipitazione (tipi di precipitazioni riconosciute: pioggia, neve, nevischio, pioggia gelata, grandine, pioviggine, senza precipitazione, codifica SYNOP 4677). L\u2019intensit\u00e0 della pioggia\/neve\/grandine e la relativa quantit\u00e0, vengono determinate a partire dalla velocit\u00e0 di caduta e dalla dimensione delle gocce. Il tipo di precipitazione \u00e8 invece determinata dalla diversa velocit\u00e0 di caduta. Il sensore ha un\u2019uscita elettrica di tipo digitale in RS485 con protocollo Modbus. Questo sensore si presta per applicazioni in svariati campi del monitoraggio ambientale ed \u00e8 particolarmente indicato per le stazioni meteorologiche campo aeronautico e stradale. Di facile installazione, non richiede alcun tipo di calibrazione periodica ed \u00e8 protetto da sovratensioni ed agenti corrosivi. Utilizzabile anche in applicazioni fotovoltaiche grazie al basso consumo energetico (standard &lt; 1 VA, con riscaldamento max 10VA)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/disdrometro-radar-tipologia-e-intensita-precipitazioni-dis\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Disdrometro tipologia e intensit\u00e0 precipitazioni - Monitoraggio strade - Nesa\" \/>\n<meta property=\"og:description\" content=\"Sensore elettronico professionale della famiglia WSxxx basato su tecnologia radar doppler a 24Ghz, in grado di determinare la precipitazione (tipi di precipitazioni riconosciute: pioggia, neve, nevischio, pioggia gelata, grandine, pioviggine, senza precipitazione, codifica SYNOP 4677). L\u2019intensit\u00e0 della pioggia\/neve\/grandine e la relativa quantit\u00e0, vengono determinate a partire dalla velocit\u00e0 di caduta e dalla dimensione delle gocce. Il tipo di precipitazione \u00e8 invece determinata dalla diversa velocit\u00e0 di caduta. Il sensore ha un\u2019uscita elettrica di tipo digitale in RS485 con protocollo Modbus. Questo sensore si presta per applicazioni in svariati campi del monitoraggio ambientale ed \u00e8 particolarmente indicato per le stazioni meteorologiche campo aeronautico e stradale. Di facile installazione, non richiede alcun tipo di calibrazione periodica ed \u00e8 protetto da sovratensioni ed agenti corrosivi. Utilizzabile anche in applicazioni fotovoltaiche grazie al basso consumo energetico (standard &lt; 1 VA, con riscaldamento max 10VA)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/disdrometro-radar-tipologia-e-intensita-precipitazioni-dis\/\" \/>\n<meta property=\"og:site_name\" content=\"Nesa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nesasrl\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-17T16:15:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2022\/02\/DIS-prev.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"989\" \/>\n\t<meta property=\"og:image:height\" content=\"989\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/disdrometro-radar-tipologia-e-intensita-precipitazioni-dis\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/disdrometro-radar-tipologia-e-intensita-precipitazioni-dis\/\",\"name\":\"Disdrometro tipologia e intensit\u00e0 precipitazioni - Monitoraggio strade - Nesa\",\"isPartOf\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\"},\"datePublished\":\"2022-01-20T13:23:03+00:00\",\"dateModified\":\"2022-12-17T16:15:01+00:00\",\"description\":\"Sensore elettronico professionale della famiglia WSxxx basato su tecnologia radar doppler a 24Ghz, in grado di determinare la precipitazione (tipi di precipitazioni riconosciute: pioggia, neve, nevischio, pioggia gelata, grandine, pioviggine, senza precipitazione, codifica SYNOP 4677). L\u2019intensit\u00e0 della pioggia\/neve\/grandine e la relativa quantit\u00e0, vengono determinate a partire dalla velocit\u00e0 di caduta e dalla dimensione delle gocce. Il tipo di precipitazione \u00e8 invece determinata dalla diversa velocit\u00e0 di caduta. Il sensore ha un\u2019uscita elettrica di tipo digitale in RS485 con protocollo Modbus. Questo sensore si presta per applicazioni in svariati campi del monitoraggio ambientale ed \u00e8 particolarmente indicato per le stazioni meteorologiche campo aeronautico e stradale. Di facile installazione, non richiede alcun tipo di calibrazione periodica ed \u00e8 protetto da sovratensioni ed agenti corrosivi. Utilizzabile anche in applicazioni fotovoltaiche grazie al basso consumo energetico (standard &lt; 1 VA, con riscaldamento max 10VA)\",\"breadcrumb\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/disdrometro-radar-tipologia-e-intensita-precipitazioni-dis\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/disdrometro-radar-tipologia-e-intensita-precipitazioni-dis\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/disdrometro-radar-tipologia-e-intensita-precipitazioni-dis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/strumenti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sensori\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/sensori\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Monitoraggio strade\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/monitoraggio-strade\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Disdrometro tipologia e intensit\u00e0 precipitazioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"name\":\"Nesa\",\"description\":\"Sistemi per il monitoraggio ambientale e telecontrollo\",\"publisher\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\",\"name\":\"Nesa srl\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"contentUrl\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"width\":264,\"height\":55,\"caption\":\"Nesa srl\"},\"image\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/nesa-srl\/\",\"https:\/\/www.facebook.com\/nesasrl\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Disdrometro tipologia e intensit\u00e0 precipitazioni - Monitoraggio strade - Nesa","description":"Sensore elettronico professionale della famiglia WSxxx basato su tecnologia radar doppler a 24Ghz, in grado di determinare la precipitazione (tipi di precipitazioni riconosciute: pioggia, neve, nevischio, pioggia gelata, grandine, pioviggine, senza precipitazione, codifica SYNOP 4677). L\u2019intensit\u00e0 della pioggia\/neve\/grandine e la relativa quantit\u00e0, vengono determinate a partire dalla velocit\u00e0 di caduta e dalla dimensione delle gocce. Il tipo di precipitazione \u00e8 invece determinata dalla diversa velocit\u00e0 di caduta. Il sensore ha un\u2019uscita elettrica di tipo digitale in RS485 con protocollo Modbus. Questo sensore si presta per applicazioni in svariati campi del monitoraggio ambientale ed \u00e8 particolarmente indicato per le stazioni meteorologiche campo aeronautico e stradale. Di facile installazione, non richiede alcun tipo di calibrazione periodica ed \u00e8 protetto da sovratensioni ed agenti corrosivi. Utilizzabile anche in applicazioni fotovoltaiche grazie al basso consumo energetico (standard &lt; 1 VA, con riscaldamento max 10VA)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/disdrometro-radar-tipologia-e-intensita-precipitazioni-dis\/","og_locale":"en_US","og_type":"article","og_title":"Disdrometro tipologia e intensit\u00e0 precipitazioni - Monitoraggio strade - Nesa","og_description":"Sensore elettronico professionale della famiglia WSxxx basato su tecnologia radar doppler a 24Ghz, in grado di determinare la precipitazione (tipi di precipitazioni riconosciute: pioggia, neve, nevischio, pioggia gelata, grandine, pioviggine, senza precipitazione, codifica SYNOP 4677). L\u2019intensit\u00e0 della pioggia\/neve\/grandine e la relativa quantit\u00e0, vengono determinate a partire dalla velocit\u00e0 di caduta e dalla dimensione delle gocce. Il tipo di precipitazione \u00e8 invece determinata dalla diversa velocit\u00e0 di caduta. Il sensore ha un\u2019uscita elettrica di tipo digitale in RS485 con protocollo Modbus. Questo sensore si presta per applicazioni in svariati campi del monitoraggio ambientale ed \u00e8 particolarmente indicato per le stazioni meteorologiche campo aeronautico e stradale. Di facile installazione, non richiede alcun tipo di calibrazione periodica ed \u00e8 protetto da sovratensioni ed agenti corrosivi. Utilizzabile anche in applicazioni fotovoltaiche grazie al basso consumo energetico (standard &lt; 1 VA, con riscaldamento max 10VA)","og_url":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/disdrometro-radar-tipologia-e-intensita-precipitazioni-dis\/","og_site_name":"Nesa","article_publisher":"https:\/\/www.facebook.com\/nesasrl","article_modified_time":"2022-12-17T16:15:01+00:00","og_image":[{"width":989,"height":989,"url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2022\/02\/DIS-prev.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/disdrometro-radar-tipologia-e-intensita-precipitazioni-dis\/","url":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/disdrometro-radar-tipologia-e-intensita-precipitazioni-dis\/","name":"Disdrometro tipologia e intensit\u00e0 precipitazioni - Monitoraggio strade - Nesa","isPartOf":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#website"},"datePublished":"2022-01-20T13:23:03+00:00","dateModified":"2022-12-17T16:15:01+00:00","description":"Sensore elettronico professionale della famiglia WSxxx basato su tecnologia radar doppler a 24Ghz, in grado di determinare la precipitazione (tipi di precipitazioni riconosciute: pioggia, neve, nevischio, pioggia gelata, grandine, pioviggine, senza precipitazione, codifica SYNOP 4677). L\u2019intensit\u00e0 della pioggia\/neve\/grandine e la relativa quantit\u00e0, vengono determinate a partire dalla velocit\u00e0 di caduta e dalla dimensione delle gocce. Il tipo di precipitazione \u00e8 invece determinata dalla diversa velocit\u00e0 di caduta. Il sensore ha un\u2019uscita elettrica di tipo digitale in RS485 con protocollo Modbus. Questo sensore si presta per applicazioni in svariati campi del monitoraggio ambientale ed \u00e8 particolarmente indicato per le stazioni meteorologiche campo aeronautico e stradale. Di facile installazione, non richiede alcun tipo di calibrazione periodica ed \u00e8 protetto da sovratensioni ed agenti corrosivi. Utilizzabile anche in applicazioni fotovoltaiche grazie al basso consumo energetico (standard &lt; 1 VA, con riscaldamento max 10VA)","breadcrumb":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/disdrometro-radar-tipologia-e-intensita-precipitazioni-dis\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nesasrl.sp2.netkom.it\/prodotti\/disdrometro-radar-tipologia-e-intensita-precipitazioni-dis\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/disdrometro-radar-tipologia-e-intensita-precipitazioni-dis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nesasrl.sp2.netkom.it\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/strumenti\/"},{"@type":"ListItem","position":3,"name":"Sensori","item":"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/sensori\/"},{"@type":"ListItem","position":4,"name":"Monitoraggio strade","item":"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/monitoraggio-strade\/"},{"@type":"ListItem","position":5,"name":"Disdrometro tipologia e intensit\u00e0 precipitazioni"}]},{"@type":"WebSite","@id":"https:\/\/nesasrl.sp2.netkom.it\/#website","url":"https:\/\/nesasrl.sp2.netkom.it\/","name":"Nesa","description":"Sistemi per il monitoraggio ambientale e telecontrollo","publisher":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization","name":"Nesa srl","url":"https:\/\/nesasrl.sp2.netkom.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/","url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","contentUrl":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","width":264,"height":55,"caption":"Nesa srl"},"image":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/nesa-srl\/","https:\/\/www.facebook.com\/nesasrl"]}]}},"_links":{"self":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/prodotti\/5778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/prodotti"}],"about":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/types\/prodotti"}],"version-history":[{"count":31,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/prodotti\/5778\/revisions"}],"predecessor-version":[{"id":19684,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/prodotti\/5778\/revisions\/19684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/media\/8903"}],"wp:attachment":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/media?parent=5778"}],"wp:term":[{"taxonomy":"categoria_prodotti","embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/categoria_prodotti?post=5778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}