{"id":5753,"date":"2022-01-20T12:39:26","date_gmt":"2022-01-20T11:39:26","guid":{"rendered":"http:\/\/164.90.193.213\/?post_type=prodotti&#038;p=5753"},"modified":"2022-12-17T17:04:42","modified_gmt":"2022-12-17T16:04:42","slug":"pluviometro-classe-a-da-1000-cm%c2%b2-pl1000","status":"publish","type":"prodotti","link":"https:\/\/nesasrl.sp2.netkom.it\/it\/prodotti\/pluviometro-classe-a-da-1000-cm%c2%b2-pl1000\/","title":{"rendered":"Pluviometro Classe A da 1000 cm\u00b2"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5753\" class=\"elementor elementor-5753\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b91e515 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b91e515\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2b7fcc0\" data-id=\"2b7fcc0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3db4bf5 elementor-widget elementor-widget-text-editor\" data-id=\"3db4bf5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Accessori correlati<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bd56de elementor-widget elementor-widget-heading\" data-id=\"0bd56de\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h3 class=\"elementor-heading-title elementor-size-default\">Questo sensore impiega\nalcuni dei nostri\naccessori<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-08594d6\" data-id=\"08594d6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83ac06f elementor--h-position-left elementor-arrows-position-outside elementor--v-position-bottom slider-nesa elementor-widget elementor-widget-slides\" data-id=\"83ac06f\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;arrows&quot;,&quot;transition_speed&quot;:300,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.7.2 - 15-06-2022 *\/\n.elementor-slides .swiper-slide-bg{background-size:cover;background-position:50%;background-repeat:no-repeat;min-width:100%;min-height:100%}.elementor-slides .swiper-slide-inner{background-repeat:no-repeat;background-position:50%;position:absolute;top:0;left:0;bottom:0;right:0;padding:50px;margin:auto}.elementor-slides .swiper-slide-inner,.elementor-slides .swiper-slide-inner:hover{color:#fff;display:-webkit-box;display:-ms-flexbox;display:flex}.elementor-slides .swiper-slide-inner .elementor-background-overlay{position:absolute;z-index:0;top:0;bottom:0;left:0;right:0}.elementor-slides .swiper-slide-inner .elementor-slide-content{position:relative;z-index:1;width:100%}.elementor-slides .swiper-slide-inner .elementor-slide-heading{font-size:35px;font-weight:700;line-height:1}.elementor-slides .swiper-slide-inner .elementor-slide-description{font-size:17px;line-height:1.4}.elementor-slides .swiper-slide-inner .elementor-slide-description:not(:last-child),.elementor-slides .swiper-slide-inner .elementor-slide-heading:not(:last-child){margin-bottom:30px}.elementor-slides .swiper-slide-inner .elementor-slide-button{border:2px solid #fff;color:#fff;background:transparent;display:inline-block}.elementor-slides .swiper-slide-inner .elementor-slide-button,.elementor-slides .swiper-slide-inner .elementor-slide-button:hover{background:transparent;color:inherit;text-decoration:none}.elementor--v-position-top .swiper-slide-inner{-webkit-box-align:start;-ms-flex-align:start;align-items:flex-start}.elementor--v-position-bottom .swiper-slide-inner{-webkit-box-align:end;-ms-flex-align:end;align-items:flex-end}.elementor--v-position-middle .swiper-slide-inner{-webkit-box-align:center;-ms-flex-align:center;align-items:center}.elementor--h-position-left .swiper-slide-inner{-webkit-box-pack:start;-ms-flex-pack:start;justify-content:flex-start}.elementor--h-position-right .swiper-slide-inner{-webkit-box-pack:end;-ms-flex-pack:end;justify-content:flex-end}.elementor--h-position-center .swiper-slide-inner{-webkit-box-pack:center;-ms-flex-pack:center;justify-content:center}body.rtl .elementor-widget-slides .elementor-swiper-button-next{left:10px;right:auto}body.rtl .elementor-widget-slides .elementor-swiper-button-prev{right:10px;left:auto}.elementor-slides-wrapper div:not(.swiper-slide)>.swiper-slide-inner{display:none}@media (max-width:767px){.elementor-slides .swiper-slide-inner{padding:30px}.elementor-slides .swiper-slide-inner .elementor-slide-heading{font-size:23px;line-height:1;margin-bottom:15px}.elementor-slides .swiper-slide-inner .elementor-slide-description{font-size:13px;line-height:1.4;margin-bottom:15px}}<\/style>\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper-container\" dir=\"ltr\" data-animation=\"fadeInRight\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-ba2c74b swiper-slide\"><div class=\"swiper-slide-bg\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/supporto-pluviometro-spl1\/\"><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Supporto pluviometro standard - SPL1<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-4f3540d swiper-slide\"><div class=\"swiper-slide-bg\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Supporto per fissaggio su superficie piana - SPL2<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-c97659d swiper-slide\"><div class=\"swiper-slide-bg\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Supporto a parete - SPL4<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-3771047 swiper-slide\"><div class=\"swiper-slide-bg\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/modulo-conversione-segnali-mcs\/\"><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Modulo conversione segnali - MCS<\/div><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>PL1000<\/p>\n","protected":false},"featured_media":5759,"template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categoria_prodotti":[51],"class_list":["post-5753","prodotti","type-prodotti","status-publish","has-post-thumbnail","hentry","categoria_prodotti-pioggia-e-neve"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pluviometro Classe A da 1000 cm\u00b2 - Pioggia e Neve - Nesa<\/title>\n<meta name=\"description\" content=\"Il pluviometro classe A PL1000 \u00e8 costituito da un corpo cilindrico in allumino anodizzato con superficie di raccolta da 1000cm\u00b2\u00a0su cui viene montato un orifizio di raccolta a forma di imbuto che attraverso un filtro convoglia l\u2019acqua verso una bascula in acciaio inox realizzata con un sistema di appoggio a lama di coltello. Un contatto reed rileva le commutazioni della bascula filtrando ogni disturbo dovuto a falsi rimbalzi. La forma delle parti meccaniche \u00e8 stata studiata per minimizzare i fenomeni che trattengono o deviano il flusso dell\u2019acqua, concentrandolo invece verso l\u2019ugello al centro. Disponibile anche nella versione riscaldata per climi freddi (mod. PL1000R) e con modulo MCS per la normalizzazione del segnale (0\u00f72Vdc, 4\u00f7 20mA, RS485\/Modbus).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/pluviometro-classe-a-da-1000-cm\u00b2-pl1000\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pluviometro Classe A da 1000 cm\u00b2 - Pioggia e Neve - Nesa\" \/>\n<meta property=\"og:description\" content=\"Il pluviometro classe A PL1000 \u00e8 costituito da un corpo cilindrico in allumino anodizzato con superficie di raccolta da 1000cm\u00b2\u00a0su cui viene montato un orifizio di raccolta a forma di imbuto che attraverso un filtro convoglia l\u2019acqua verso una bascula in acciaio inox realizzata con un sistema di appoggio a lama di coltello. Un contatto reed rileva le commutazioni della bascula filtrando ogni disturbo dovuto a falsi rimbalzi. La forma delle parti meccaniche \u00e8 stata studiata per minimizzare i fenomeni che trattengono o deviano il flusso dell\u2019acqua, concentrandolo invece verso l\u2019ugello al centro. Disponibile anche nella versione riscaldata per climi freddi (mod. PL1000R) e con modulo MCS per la normalizzazione del segnale (0\u00f72Vdc, 4\u00f7 20mA, RS485\/Modbus).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/pluviometro-classe-a-da-1000-cm\u00b2-pl1000\/\" \/>\n<meta property=\"og:site_name\" content=\"Nesa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nesasrl\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-17T16:04:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2022\/01\/strumenti-sensori-pioggia-neve_PL1000.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/pluviometro-classe-a-da-1000-cm%c2%b2-pl1000\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/pluviometro-classe-a-da-1000-cm%c2%b2-pl1000\/\",\"name\":\"Pluviometro Classe A da 1000 cm\u00b2 - Pioggia e Neve - Nesa\",\"isPartOf\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\"},\"datePublished\":\"2022-01-20T11:39:26+00:00\",\"dateModified\":\"2022-12-17T16:04:42+00:00\",\"description\":\"Il pluviometro classe A PL1000 \u00e8 costituito da un corpo cilindrico in allumino anodizzato con superficie di raccolta da 1000cm\u00b2\u00a0su cui viene montato un orifizio di raccolta a forma di imbuto che attraverso un filtro convoglia l\u2019acqua verso una bascula in acciaio inox realizzata con un sistema di appoggio a lama di coltello. Un contatto reed rileva le commutazioni della bascula filtrando ogni disturbo dovuto a falsi rimbalzi. La forma delle parti meccaniche \u00e8 stata studiata per minimizzare i fenomeni che trattengono o deviano il flusso dell\u2019acqua, concentrandolo invece verso l\u2019ugello al centro. Disponibile anche nella versione riscaldata per climi freddi (mod. PL1000R) e con modulo MCS per la normalizzazione del segnale (0\u00f72Vdc, 4\u00f7 20mA, RS485\/Modbus).\",\"breadcrumb\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/pluviometro-classe-a-da-1000-cm%c2%b2-pl1000\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/pluviometro-classe-a-da-1000-cm%c2%b2-pl1000\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/pluviometro-classe-a-da-1000-cm%c2%b2-pl1000\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/strumenti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sensori\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/sensori\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Pioggia e Neve\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/pioggia-e-neve\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Pluviometro Classe A da 1000 cm\u00b2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"name\":\"Nesa\",\"description\":\"Sistemi per il monitoraggio ambientale e telecontrollo\",\"publisher\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\",\"name\":\"Nesa srl\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"contentUrl\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"width\":264,\"height\":55,\"caption\":\"Nesa srl\"},\"image\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/nesa-srl\/\",\"https:\/\/www.facebook.com\/nesasrl\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pluviometro Classe A da 1000 cm\u00b2 - Pioggia e Neve - Nesa","description":"Il pluviometro classe A PL1000 \u00e8 costituito da un corpo cilindrico in allumino anodizzato con superficie di raccolta da 1000cm\u00b2\u00a0su cui viene montato un orifizio di raccolta a forma di imbuto che attraverso un filtro convoglia l\u2019acqua verso una bascula in acciaio inox realizzata con un sistema di appoggio a lama di coltello. Un contatto reed rileva le commutazioni della bascula filtrando ogni disturbo dovuto a falsi rimbalzi. La forma delle parti meccaniche \u00e8 stata studiata per minimizzare i fenomeni che trattengono o deviano il flusso dell\u2019acqua, concentrandolo invece verso l\u2019ugello al centro. Disponibile anche nella versione riscaldata per climi freddi (mod. PL1000R) e con modulo MCS per la normalizzazione del segnale (0\u00f72Vdc, 4\u00f7 20mA, RS485\/Modbus).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/pluviometro-classe-a-da-1000-cm\u00b2-pl1000\/","og_locale":"en_US","og_type":"article","og_title":"Pluviometro Classe A da 1000 cm\u00b2 - Pioggia e Neve - Nesa","og_description":"Il pluviometro classe A PL1000 \u00e8 costituito da un corpo cilindrico in allumino anodizzato con superficie di raccolta da 1000cm\u00b2\u00a0su cui viene montato un orifizio di raccolta a forma di imbuto che attraverso un filtro convoglia l\u2019acqua verso una bascula in acciaio inox realizzata con un sistema di appoggio a lama di coltello. Un contatto reed rileva le commutazioni della bascula filtrando ogni disturbo dovuto a falsi rimbalzi. La forma delle parti meccaniche \u00e8 stata studiata per minimizzare i fenomeni che trattengono o deviano il flusso dell\u2019acqua, concentrandolo invece verso l\u2019ugello al centro. Disponibile anche nella versione riscaldata per climi freddi (mod. PL1000R) e con modulo MCS per la normalizzazione del segnale (0\u00f72Vdc, 4\u00f7 20mA, RS485\/Modbus).","og_url":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/pluviometro-classe-a-da-1000-cm\u00b2-pl1000\/","og_site_name":"Nesa","article_publisher":"https:\/\/www.facebook.com\/nesasrl","article_modified_time":"2022-12-17T16:04:42+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2022\/01\/strumenti-sensori-pioggia-neve_PL1000.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/pluviometro-classe-a-da-1000-cm%c2%b2-pl1000\/","url":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/pluviometro-classe-a-da-1000-cm%c2%b2-pl1000\/","name":"Pluviometro Classe A da 1000 cm\u00b2 - Pioggia e Neve - Nesa","isPartOf":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#website"},"datePublished":"2022-01-20T11:39:26+00:00","dateModified":"2022-12-17T16:04:42+00:00","description":"Il pluviometro classe A PL1000 \u00e8 costituito da un corpo cilindrico in allumino anodizzato con superficie di raccolta da 1000cm\u00b2\u00a0su cui viene montato un orifizio di raccolta a forma di imbuto che attraverso un filtro convoglia l\u2019acqua verso una bascula in acciaio inox realizzata con un sistema di appoggio a lama di coltello. Un contatto reed rileva le commutazioni della bascula filtrando ogni disturbo dovuto a falsi rimbalzi. La forma delle parti meccaniche \u00e8 stata studiata per minimizzare i fenomeni che trattengono o deviano il flusso dell\u2019acqua, concentrandolo invece verso l\u2019ugello al centro. Disponibile anche nella versione riscaldata per climi freddi (mod. PL1000R) e con modulo MCS per la normalizzazione del segnale (0\u00f72Vdc, 4\u00f7 20mA, RS485\/Modbus).","breadcrumb":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/pluviometro-classe-a-da-1000-cm%c2%b2-pl1000\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nesasrl.sp2.netkom.it\/prodotti\/pluviometro-classe-a-da-1000-cm%c2%b2-pl1000\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/pluviometro-classe-a-da-1000-cm%c2%b2-pl1000\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nesasrl.sp2.netkom.it\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/strumenti\/"},{"@type":"ListItem","position":3,"name":"Sensori","item":"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/sensori\/"},{"@type":"ListItem","position":4,"name":"Pioggia e Neve","item":"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/pioggia-e-neve\/"},{"@type":"ListItem","position":5,"name":"Pluviometro Classe A da 1000 cm\u00b2"}]},{"@type":"WebSite","@id":"https:\/\/nesasrl.sp2.netkom.it\/#website","url":"https:\/\/nesasrl.sp2.netkom.it\/","name":"Nesa","description":"Sistemi per il monitoraggio ambientale e telecontrollo","publisher":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization","name":"Nesa srl","url":"https:\/\/nesasrl.sp2.netkom.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/","url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","contentUrl":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","width":264,"height":55,"caption":"Nesa srl"},"image":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/nesa-srl\/","https:\/\/www.facebook.com\/nesasrl"]}]}},"_links":{"self":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/prodotti\/5753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/prodotti"}],"about":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/types\/prodotti"}],"version-history":[{"count":24,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/prodotti\/5753\/revisions"}],"predecessor-version":[{"id":19646,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/prodotti\/5753\/revisions\/19646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/media\/5759"}],"wp:attachment":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/media?parent=5753"}],"wp:term":[{"taxonomy":"categoria_prodotti","embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/categoria_prodotti?post=5753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}