{"id":3873,"date":"2021-11-02T15:38:49","date_gmt":"2021-11-02T14:38:49","guid":{"rendered":"http:\/\/164.90.193.213\/?post_type=prodotti&#038;p=3873"},"modified":"2022-04-04T11:45:41","modified_gmt":"2022-04-04T09:45:41","slug":"iris","status":"publish","type":"prodotti","link":"https:\/\/nesasrl.sp2.netkom.it\/it\/prodotti\/iris\/","title":{"rendered":"Iris"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":3876,"template":"elementor_theme","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categoria_prodotti":[49],"class_list":["post-3873","prodotti","type-prodotti","status-publish","has-post-thumbnail","hentry","categoria_prodotti-software"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Iris - Software - Nesa<\/title>\n<meta name=\"description\" content=\"Applicativo Web per la gestione dati da una singola stazione di misura. Non richiede database e non richiede installazione. Pu\u00f2 essere fatto girare su una singola macchina o reso accessibile in rete intranet\/internet.   Prelievo dati automatico da area FTP o direttamente dal datalogger.  Visualizzazione ultimi dati istantanei in formato numerico e simbolico  Visualizzazione storico dati in formato grafico dinamico con possibilit\u00e0 di iterazione  Scarico dati direttamente da sito in formato Excel\u00ae.  Visualizzazione Rosa dei Venti  Rappresentazione del punto geografico del sistema di acquisizione su cartografia tipo Google Maps  Visualizzazione immagini da telecamera collegata al datalogger della serie TMF.  Possibilit\u00e0 di personalizzare le pagine web con loghi e testo del cliente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/iris\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iris - Software - Nesa\" \/>\n<meta property=\"og:description\" content=\"Applicativo Web per la gestione dati da una singola stazione di misura. Non richiede database e non richiede installazione. Pu\u00f2 essere fatto girare su una singola macchina o reso accessibile in rete intranet\/internet.   Prelievo dati automatico da area FTP o direttamente dal datalogger.  Visualizzazione ultimi dati istantanei in formato numerico e simbolico  Visualizzazione storico dati in formato grafico dinamico con possibilit\u00e0 di iterazione  Scarico dati direttamente da sito in formato Excel\u00ae.  Visualizzazione Rosa dei Venti  Rappresentazione del punto geografico del sistema di acquisizione su cartografia tipo Google Maps  Visualizzazione immagini da telecamera collegata al datalogger della serie TMF.  Possibilit\u00e0 di personalizzare le pagine web con loghi e testo del cliente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/iris\/\" \/>\n<meta property=\"og:site_name\" content=\"Nesa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nesasrl\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-04T09:45:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/Iris_prev.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/iris\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/iris\/\",\"name\":\"Iris - Software - Nesa\",\"isPartOf\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\"},\"datePublished\":\"2021-11-02T14:38:49+00:00\",\"dateModified\":\"2022-04-04T09:45:41+00:00\",\"description\":\"Applicativo Web per la gestione dati da una singola stazione di misura. Non richiede database e non richiede installazione. Pu\u00f2 essere fatto girare su una singola macchina o reso accessibile in rete intranet\/internet. \u2022 Prelievo dati automatico da area FTP o direttamente dal datalogger. \u2022 Visualizzazione ultimi dati istantanei in formato numerico e simbolico \u2022 Visualizzazione storico dati in formato grafico dinamico con possibilit\u00e0 di iterazione \u2022 Scarico dati direttamente da sito in formato Excel\u00ae. \u2022 Visualizzazione Rosa dei Venti \u2022 Rappresentazione del punto geografico del sistema di acquisizione su cartografia tipo Google Maps \u2022 Visualizzazione immagini da telecamera collegata al datalogger della serie TMF. \u2022 Possibilit\u00e0 di personalizzare le pagine web con loghi e testo del cliente.\",\"breadcrumb\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/iris\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/iris\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/iris\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/strumenti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Software\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/software\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Iris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"name\":\"Nesa\",\"description\":\"Sistemi per il monitoraggio ambientale e telecontrollo\",\"publisher\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\",\"name\":\"Nesa srl\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"contentUrl\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"width\":264,\"height\":55,\"caption\":\"Nesa srl\"},\"image\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/nesa-srl\/\",\"https:\/\/www.facebook.com\/nesasrl\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Iris - Software - Nesa","description":"Applicativo Web per la gestione dati da una singola stazione di misura. Non richiede database e non richiede installazione. Pu\u00f2 essere fatto girare su una singola macchina o reso accessibile in rete intranet\/internet.   Prelievo dati automatico da area FTP o direttamente dal datalogger.  Visualizzazione ultimi dati istantanei in formato numerico e simbolico  Visualizzazione storico dati in formato grafico dinamico con possibilit\u00e0 di iterazione  Scarico dati direttamente da sito in formato Excel\u00ae.  Visualizzazione Rosa dei Venti  Rappresentazione del punto geografico del sistema di acquisizione su cartografia tipo Google Maps  Visualizzazione immagini da telecamera collegata al datalogger della serie TMF.  Possibilit\u00e0 di personalizzare le pagine web con loghi e testo del cliente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/iris\/","og_locale":"en_US","og_type":"article","og_title":"Iris - Software - Nesa","og_description":"Applicativo Web per la gestione dati da una singola stazione di misura. Non richiede database e non richiede installazione. Pu\u00f2 essere fatto girare su una singola macchina o reso accessibile in rete intranet\/internet.   Prelievo dati automatico da area FTP o direttamente dal datalogger.  Visualizzazione ultimi dati istantanei in formato numerico e simbolico  Visualizzazione storico dati in formato grafico dinamico con possibilit\u00e0 di iterazione  Scarico dati direttamente da sito in formato Excel\u00ae.  Visualizzazione Rosa dei Venti  Rappresentazione del punto geografico del sistema di acquisizione su cartografia tipo Google Maps  Visualizzazione immagini da telecamera collegata al datalogger della serie TMF.  Possibilit\u00e0 di personalizzare le pagine web con loghi e testo del cliente.","og_url":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/iris\/","og_site_name":"Nesa","article_publisher":"https:\/\/www.facebook.com\/nesasrl","article_modified_time":"2022-04-04T09:45:41+00:00","og_image":[{"width":550,"height":700,"url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/Iris_prev.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/iris\/","url":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/iris\/","name":"Iris - Software - Nesa","isPartOf":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#website"},"datePublished":"2021-11-02T14:38:49+00:00","dateModified":"2022-04-04T09:45:41+00:00","description":"Applicativo Web per la gestione dati da una singola stazione di misura. Non richiede database e non richiede installazione. Pu\u00f2 essere fatto girare su una singola macchina o reso accessibile in rete intranet\/internet. \u2022 Prelievo dati automatico da area FTP o direttamente dal datalogger. \u2022 Visualizzazione ultimi dati istantanei in formato numerico e simbolico \u2022 Visualizzazione storico dati in formato grafico dinamico con possibilit\u00e0 di iterazione \u2022 Scarico dati direttamente da sito in formato Excel\u00ae. \u2022 Visualizzazione Rosa dei Venti \u2022 Rappresentazione del punto geografico del sistema di acquisizione su cartografia tipo Google Maps \u2022 Visualizzazione immagini da telecamera collegata al datalogger della serie TMF. \u2022 Possibilit\u00e0 di personalizzare le pagine web con loghi e testo del cliente.","breadcrumb":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/iris\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nesasrl.sp2.netkom.it\/prodotti\/iris\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/iris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nesasrl.sp2.netkom.it\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/strumenti\/"},{"@type":"ListItem","position":3,"name":"Software","item":"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/software\/"},{"@type":"ListItem","position":4,"name":"Iris"}]},{"@type":"WebSite","@id":"https:\/\/nesasrl.sp2.netkom.it\/#website","url":"https:\/\/nesasrl.sp2.netkom.it\/","name":"Nesa","description":"Sistemi per il monitoraggio ambientale e telecontrollo","publisher":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization","name":"Nesa srl","url":"https:\/\/nesasrl.sp2.netkom.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/","url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","contentUrl":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","width":264,"height":55,"caption":"Nesa srl"},"image":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/nesa-srl\/","https:\/\/www.facebook.com\/nesasrl"]}]}},"_links":{"self":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/prodotti\/3873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/prodotti"}],"about":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/types\/prodotti"}],"version-history":[{"count":7,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/prodotti\/3873\/revisions"}],"predecessor-version":[{"id":12642,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/prodotti\/3873\/revisions\/12642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/media\/3876"}],"wp:attachment":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/media?parent=3873"}],"wp:term":[{"taxonomy":"categoria_prodotti","embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/categoria_prodotti?post=3873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}