{"id":3494,"date":"2021-10-29T12:45:45","date_gmt":"2021-10-29T10:45:45","guid":{"rendered":"http:\/\/164.90.193.213\/?post_type=prodotti&#038;p=3494"},"modified":"2022-06-13T08:54:16","modified_gmt":"2022-06-13T06:54:16","slug":"sistemi-di-trasmissione-iot-4-0","status":"publish","type":"prodotti","link":"https:\/\/nesasrl.sp2.netkom.it\/it\/prodotti\/sistemi-di-trasmissione-iot-4-0\/","title":{"rendered":"Sistemi di trasmissione 4.0"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3494\" class=\"elementor elementor-3494\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3796ac3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3796ac3\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b64e370\" data-id=\"b64e370\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a127ec elementor-widget elementor-widget-text-editor\" data-id=\"5a127ec\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Prodotti correlati<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24b9c10 elementor-widget elementor-widget-heading\" data-id=\"24b9c10\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h3 class=\"elementor-heading-title elementor-size-default\">Questo sistema impiega alcuni dei nostri prodotti<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8be8642\" data-id=\"8be8642\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f0be02 elementor--h-position-left elementor-arrows-position-outside elementor--v-position-bottom slider-nesa elementor-widget elementor-widget-slides\" data-id=\"0f0be02\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;arrows&quot;,&quot;transition_speed&quot;:300,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.7.2 - 15-06-2022 *\/\n.elementor-slides .swiper-slide-bg{background-size:cover;background-position:50%;background-repeat:no-repeat;min-width:100%;min-height:100%}.elementor-slides .swiper-slide-inner{background-repeat:no-repeat;background-position:50%;position:absolute;top:0;left:0;bottom:0;right:0;padding:50px;margin:auto}.elementor-slides .swiper-slide-inner,.elementor-slides .swiper-slide-inner:hover{color:#fff;display:-webkit-box;display:-ms-flexbox;display:flex}.elementor-slides .swiper-slide-inner .elementor-background-overlay{position:absolute;z-index:0;top:0;bottom:0;left:0;right:0}.elementor-slides .swiper-slide-inner .elementor-slide-content{position:relative;z-index:1;width:100%}.elementor-slides .swiper-slide-inner .elementor-slide-heading{font-size:35px;font-weight:700;line-height:1}.elementor-slides .swiper-slide-inner .elementor-slide-description{font-size:17px;line-height:1.4}.elementor-slides .swiper-slide-inner .elementor-slide-description:not(:last-child),.elementor-slides .swiper-slide-inner .elementor-slide-heading:not(:last-child){margin-bottom:30px}.elementor-slides .swiper-slide-inner .elementor-slide-button{border:2px solid #fff;color:#fff;background:transparent;display:inline-block}.elementor-slides .swiper-slide-inner .elementor-slide-button,.elementor-slides .swiper-slide-inner .elementor-slide-button:hover{background:transparent;color:inherit;text-decoration:none}.elementor--v-position-top .swiper-slide-inner{-webkit-box-align:start;-ms-flex-align:start;align-items:flex-start}.elementor--v-position-bottom .swiper-slide-inner{-webkit-box-align:end;-ms-flex-align:end;align-items:flex-end}.elementor--v-position-middle .swiper-slide-inner{-webkit-box-align:center;-ms-flex-align:center;align-items:center}.elementor--h-position-left .swiper-slide-inner{-webkit-box-pack:start;-ms-flex-pack:start;justify-content:flex-start}.elementor--h-position-right .swiper-slide-inner{-webkit-box-pack:end;-ms-flex-pack:end;justify-content:flex-end}.elementor--h-position-center .swiper-slide-inner{-webkit-box-pack:center;-ms-flex-pack:center;justify-content:center}body.rtl .elementor-widget-slides .elementor-swiper-button-next{left:10px;right:auto}body.rtl .elementor-widget-slides .elementor-swiper-button-prev{right:10px;left:auto}.elementor-slides-wrapper div:not(.swiper-slide)>.swiper-slide-inner{display:none}@media (max-width:767px){.elementor-slides .swiper-slide-inner{padding:30px}.elementor-slides .swiper-slide-inner .elementor-slide-heading{font-size:23px;line-height:1;margin-bottom:15px}.elementor-slides .swiper-slide-inner .elementor-slide-description{font-size:13px;line-height:1.4;margin-bottom:15px}}<\/style>\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper-container\" dir=\"ltr\" data-animation=\"fadeInRight\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-ba2c74b swiper-slide\"><div class=\"swiper-slide-bg\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/interfaccia-radio-iot-per-sensori-analogici-e-digitali-sfl\/\"><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Interfaccia di acquisizione dati IoT - SFL<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-76e45cc swiper-slide\"><div class=\"swiper-slide-bg\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/stazione-agrometeorologica-quido\/\"><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Stazione agrometeo compatta - Quido<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-b48f9b6 swiper-slide\"><div class=\"swiper-slide-bg\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.spidersystem.eu\/it\/\"><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Sistema di allertamento Spider System<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-ed4d0ee swiper-slide\"><div class=\"swiper-slide-bg\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/stazione-gelate-tardive-chione\/\"><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Stazione per allerta gelate - Chione<\/div><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sistemi IoT<\/p>\n","protected":false},"featured_media":9362,"template":"elementor_theme","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categoria_prodotti":[34],"class_list":["post-3494","prodotti","type-prodotti","status-publish","has-post-thumbnail","hentry","categoria_prodotti-iot-4-0"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sistemi di trasmissione 4.0 - IoT 4.0 - Nesa<\/title>\n<meta name=\"description\" content=\"I nostri sistemi prevedono la realizzazione di reti composte da uno a numerosissimi sensori, in grado di inviare contemporaneamente i dati ad un servizio cloud, a cui \u00e8 possibile accedere via web e tramite APP. L&#039;elevata frequenza di invio delle misure e la grande capacit\u00e0 del database, offrono un nuovo concetto di monitoraggio che prescinde dai limiti delle precedenti tecnologie basate sui datalogger. Ogni modifica, allarme, calibrazione del dato avviene direttamente sul database in cloud.  Nessuna perdita dei dati, nessun limite temporale di accesso, fruibilit\u00e0 delle informazioni come mai avvenuto prima. Proponiamo soluzioni complete, dal singolo sensore a reti di monitoraggio, incluso il software di gestione e visualizzazione in cloud e la APP per dispositivi mobili.  I nostri dispositivi, grazie alla molteplicit\u00e0 dei protocolli integrati, non risentono della mancanza di ponti radio o di copertura, consentendo di realizzare reti ad alta ridondanza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/sistemi-di-trasmissione-iot-4-0\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sistemi di trasmissione 4.0 - IoT 4.0 - Nesa\" \/>\n<meta property=\"og:description\" content=\"I nostri sistemi prevedono la realizzazione di reti composte da uno a numerosissimi sensori, in grado di inviare contemporaneamente i dati ad un servizio cloud, a cui \u00e8 possibile accedere via web e tramite APP. L&#039;elevata frequenza di invio delle misure e la grande capacit\u00e0 del database, offrono un nuovo concetto di monitoraggio che prescinde dai limiti delle precedenti tecnologie basate sui datalogger. Ogni modifica, allarme, calibrazione del dato avviene direttamente sul database in cloud.  Nessuna perdita dei dati, nessun limite temporale di accesso, fruibilit\u00e0 delle informazioni come mai avvenuto prima. Proponiamo soluzioni complete, dal singolo sensore a reti di monitoraggio, incluso il software di gestione e visualizzazione in cloud e la APP per dispositivi mobili.  I nostri dispositivi, grazie alla molteplicit\u00e0 dei protocolli integrati, non risentono della mancanza di ponti radio o di copertura, consentendo di realizzare reti ad alta ridondanza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/sistemi-di-trasmissione-iot-4-0\/\" \/>\n<meta property=\"og:site_name\" content=\"Nesa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nesasrl\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-13T06:54:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2022\/02\/iot-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1309\" \/>\n\t<meta property=\"og:image:height\" content=\"1318\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/sistemi-di-trasmissione-iot-4-0\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/sistemi-di-trasmissione-iot-4-0\/\",\"name\":\"Sistemi di trasmissione 4.0 - IoT 4.0 - Nesa\",\"isPartOf\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\"},\"datePublished\":\"2021-10-29T10:45:45+00:00\",\"dateModified\":\"2022-06-13T06:54:16+00:00\",\"description\":\"I nostri sistemi prevedono la realizzazione di reti composte da uno a numerosissimi sensori, in grado di inviare contemporaneamente i dati ad un servizio cloud, a cui \u00e8 possibile accedere via web e tramite APP. L'elevata frequenza di invio delle misure e la grande capacit\u00e0 del database, offrono un nuovo concetto di monitoraggio che prescinde dai limiti delle precedenti tecnologie basate sui datalogger. Ogni modifica, allarme, calibrazione del dato avviene direttamente sul database in cloud. Nessuna perdita dei dati, nessun limite temporale di accesso, fruibilit\u00e0 delle informazioni come mai avvenuto prima. Proponiamo soluzioni complete, dal singolo sensore a reti di monitoraggio, incluso il software di gestione e visualizzazione in cloud e la APP per dispositivi mobili. I nostri dispositivi, grazie alla molteplicit\u00e0 dei protocolli integrati, non risentono della mancanza di ponti radio o di copertura, consentendo di realizzare reti ad alta ridondanza.\",\"breadcrumb\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/sistemi-di-trasmissione-iot-4-0\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/sistemi-di-trasmissione-iot-4-0\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/sistemi-di-trasmissione-iot-4-0\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sistemi\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/sistemi\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"IoT 4.0\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/iot-4-0\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Sistemi di trasmissione 4.0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"name\":\"Nesa\",\"description\":\"Sistemi per il monitoraggio ambientale e telecontrollo\",\"publisher\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\",\"name\":\"Nesa srl\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"contentUrl\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"width\":264,\"height\":55,\"caption\":\"Nesa srl\"},\"image\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/nesa-srl\/\",\"https:\/\/www.facebook.com\/nesasrl\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sistemi di trasmissione 4.0 - IoT 4.0 - Nesa","description":"I nostri sistemi prevedono la realizzazione di reti composte da uno a numerosissimi sensori, in grado di inviare contemporaneamente i dati ad un servizio cloud, a cui \u00e8 possibile accedere via web e tramite APP. L'elevata frequenza di invio delle misure e la grande capacit\u00e0 del database, offrono un nuovo concetto di monitoraggio che prescinde dai limiti delle precedenti tecnologie basate sui datalogger. Ogni modifica, allarme, calibrazione del dato avviene direttamente sul database in cloud.  Nessuna perdita dei dati, nessun limite temporale di accesso, fruibilit\u00e0 delle informazioni come mai avvenuto prima. Proponiamo soluzioni complete, dal singolo sensore a reti di monitoraggio, incluso il software di gestione e visualizzazione in cloud e la APP per dispositivi mobili.  I nostri dispositivi, grazie alla molteplicit\u00e0 dei protocolli integrati, non risentono della mancanza di ponti radio o di copertura, consentendo di realizzare reti ad alta ridondanza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/sistemi-di-trasmissione-iot-4-0\/","og_locale":"en_US","og_type":"article","og_title":"Sistemi di trasmissione 4.0 - IoT 4.0 - Nesa","og_description":"I nostri sistemi prevedono la realizzazione di reti composte da uno a numerosissimi sensori, in grado di inviare contemporaneamente i dati ad un servizio cloud, a cui \u00e8 possibile accedere via web e tramite APP. L'elevata frequenza di invio delle misure e la grande capacit\u00e0 del database, offrono un nuovo concetto di monitoraggio che prescinde dai limiti delle precedenti tecnologie basate sui datalogger. Ogni modifica, allarme, calibrazione del dato avviene direttamente sul database in cloud.  Nessuna perdita dei dati, nessun limite temporale di accesso, fruibilit\u00e0 delle informazioni come mai avvenuto prima. Proponiamo soluzioni complete, dal singolo sensore a reti di monitoraggio, incluso il software di gestione e visualizzazione in cloud e la APP per dispositivi mobili.  I nostri dispositivi, grazie alla molteplicit\u00e0 dei protocolli integrati, non risentono della mancanza di ponti radio o di copertura, consentendo di realizzare reti ad alta ridondanza.","og_url":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/sistemi-di-trasmissione-iot-4-0\/","og_site_name":"Nesa","article_publisher":"https:\/\/www.facebook.com\/nesasrl","article_modified_time":"2022-06-13T06:54:16+00:00","og_image":[{"width":1309,"height":1318,"url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2022\/02\/iot-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/sistemi-di-trasmissione-iot-4-0\/","url":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/sistemi-di-trasmissione-iot-4-0\/","name":"Sistemi di trasmissione 4.0 - IoT 4.0 - Nesa","isPartOf":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#website"},"datePublished":"2021-10-29T10:45:45+00:00","dateModified":"2022-06-13T06:54:16+00:00","description":"I nostri sistemi prevedono la realizzazione di reti composte da uno a numerosissimi sensori, in grado di inviare contemporaneamente i dati ad un servizio cloud, a cui \u00e8 possibile accedere via web e tramite APP. L'elevata frequenza di invio delle misure e la grande capacit\u00e0 del database, offrono un nuovo concetto di monitoraggio che prescinde dai limiti delle precedenti tecnologie basate sui datalogger. Ogni modifica, allarme, calibrazione del dato avviene direttamente sul database in cloud. Nessuna perdita dei dati, nessun limite temporale di accesso, fruibilit\u00e0 delle informazioni come mai avvenuto prima. Proponiamo soluzioni complete, dal singolo sensore a reti di monitoraggio, incluso il software di gestione e visualizzazione in cloud e la APP per dispositivi mobili. I nostri dispositivi, grazie alla molteplicit\u00e0 dei protocolli integrati, non risentono della mancanza di ponti radio o di copertura, consentendo di realizzare reti ad alta ridondanza.","breadcrumb":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/sistemi-di-trasmissione-iot-4-0\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nesasrl.sp2.netkom.it\/prodotti\/sistemi-di-trasmissione-iot-4-0\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/sistemi-di-trasmissione-iot-4-0\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nesasrl.sp2.netkom.it\/it\/"},{"@type":"ListItem","position":2,"name":"Sistemi","item":"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/sistemi\/"},{"@type":"ListItem","position":3,"name":"IoT 4.0","item":"https:\/\/nesasrl.sp2.netkom.it\/categoria_prodotti\/iot-4-0\/"},{"@type":"ListItem","position":4,"name":"Sistemi di trasmissione 4.0"}]},{"@type":"WebSite","@id":"https:\/\/nesasrl.sp2.netkom.it\/#website","url":"https:\/\/nesasrl.sp2.netkom.it\/","name":"Nesa","description":"Sistemi per il monitoraggio ambientale e telecontrollo","publisher":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization","name":"Nesa srl","url":"https:\/\/nesasrl.sp2.netkom.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/","url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","contentUrl":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","width":264,"height":55,"caption":"Nesa srl"},"image":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/nesa-srl\/","https:\/\/www.facebook.com\/nesasrl"]}]}},"_links":{"self":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/prodotti\/3494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/prodotti"}],"about":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/types\/prodotti"}],"version-history":[{"count":53,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/prodotti\/3494\/revisions"}],"predecessor-version":[{"id":15391,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/prodotti\/3494\/revisions\/15391"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/media\/9362"}],"wp:attachment":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/media?parent=3494"}],"wp:term":[{"taxonomy":"categoria_prodotti","embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/categoria_prodotti?post=3494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}