{"id":3499,"date":"2014-09-17T12:47:00","date_gmt":"2014-09-17T10:47:00","guid":{"rendered":"http:\/\/164.90.193.213\/?p=3499"},"modified":"2023-03-01T09:31:16","modified_gmt":"2023-03-01T08:31:16","slug":"nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle","status":"publish","type":"post","link":"https:\/\/nesasrl.sp2.netkom.it\/it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/","title":{"rendered":"NESA e GESTIONI ELETTRONICHE presentano la SMTT presso il RESMA di Vigna di Valle"},"content":{"rendered":"\n<p>Nesa SRL e Gestioni Elettroniche SPA nuovamente operativi presso Vigna di Valle sul lago di Bracciano (sede del\u00a0Reparto Sperimentazioni di Meteorologia Aeronautica,\u00a0<strong>ReSMA) con la presentazione della proposta di Stazione Meteorologica Trasportabile Tattica, a norma WMO, dotata di\u00a0sensoristica intelligente con protocollo seriale<\/strong>. La stazione si trasporta in massimo tre casse industriali di categoria ATA-300 e non necessita di strumenti meccanici per l&#8217;installazione\/disinstallazione.<strong> I tempi operativi sono di massimo 15 minuti<\/strong> per ciascuna operazione, e tale velocit\u00e0 risponde perfettamente alle esigenze di trasportabilit\u00e0, modularit\u00e0 e flessibilit\u00e0 degli apparati di misura per missioni temporanee. La stazione \u00e8 equipaggiata con un <strong>palo tattico avvolgibile ed estremamente resistente<\/strong>, adatto per applicazioni in spazi ridotti e con tempistiche ristrette; il box in acciaio INOX presenta tutti i connettori IP68 sul lato posteriore, in tal modo <strong>non \u00e8 necessario aprire la porta<\/strong>\u00a0frontale se non per accedere all&#8217;interruttore di accensione. Capacit\u00e0 di <strong>self-recognizing sulla tipologia di alimentazione<\/strong> e interfacciabilit\u00e0 con ogni dispositivo di misura (anche di terze parti), rendono la <strong>SMTT un prezioso mezzo di supporto per l&#8217;ambito militare<\/strong>, che permette immediata operabilit\u00e0, semplice ed intuitiva modalit\u00e0 di installazione, ridottissimi tempi di azione.\u00a0<br><br>Ancora una volta la <strong>tecnologia e il know-how tutto italiano<\/strong>, grazie alla\u00a0<strong>perfetta sinergia tra Nesa e Gestioni Elettroniche,<\/strong> hanno permesso la realizzazione di un prodotto adeguato alle esigenze del settore Aeronautico, spingendo ulteriormente sulle gi\u00e0 avanzate tecniche di costruzione e impiego della sensoristica professionale nonch\u00e9 dei sistemi di gestione dati.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"480\" src=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/10\/vigna-di_valle_nesa2013_01.jpg\" alt=\"\" class=\"wp-image-3500\" srcset=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/10\/vigna-di_valle_nesa2013_01.jpg 360w, https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/10\/vigna-di_valle_nesa2013_01-225x300.jpg 225w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesa SRL e Gestioni Elettroniche SPA nuovamente operativi presso Vigna di Valle sul lago di Bracciano (sede del\u00a0Reparto Sperimentazioni di Meteorologia Aeronautica,\u00a0ReSMA) con la presentazione della proposta di Stazione Meteorologica Trasportabile Tattica, a norma WMO, dotata di\u00a0sensoristica intelligente con protocollo seriale. La stazione si trasporta in massimo tre casse industriali di categoria ATA-300 e non &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/nesasrl.sp2.netkom.it\/it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/\"> <span class=\"screen-reader-text\">NESA e GESTIONI ELETTRONICHE presentano la SMTT presso il RESMA di Vigna di Valle<\/span> Read More &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":3502,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-3499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-varie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>NESA e GESTIONI ELETTRONICHE presentano la SMTT presso il RESMA di Vigna di Valle - Nesa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nesasrl.sp2.netkom.it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NESA e GESTIONI ELETTRONICHE presentano la SMTT presso il RESMA di Vigna di Valle - Nesa\" \/>\n<meta property=\"og:description\" content=\"Nesa SRL e Gestioni Elettroniche SPA nuovamente operativi presso Vigna di Valle sul lago di Bracciano (sede del\u00a0Reparto Sperimentazioni di Meteorologia Aeronautica,\u00a0ReSMA) con la presentazione della proposta di Stazione Meteorologica Trasportabile Tattica, a norma WMO, dotata di\u00a0sensoristica intelligente con protocollo seriale. La stazione si trasporta in massimo tre casse industriali di categoria ATA-300 e non &hellip; NESA e GESTIONI ELETTRONICHE presentano la SMTT presso il RESMA di Vigna di Valle Read More &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nesasrl.sp2.netkom.it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/\" \/>\n<meta property=\"og:site_name\" content=\"Nesa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nesasrl\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-17T10:47:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-01T08:31:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/10\/vigna-di_valle_nesa2013_prew.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@moris\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"moris\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/\"},\"author\":{\"name\":\"moris\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/person\/f04f829b25d9803bd3039afd4b37395a\"},\"headline\":\"NESA e GESTIONI ELETTRONICHE presentano la SMTT presso il RESMA di Vigna di Valle\",\"datePublished\":\"2014-09-17T10:47:00+00:00\",\"dateModified\":\"2023-03-01T08:31:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/\"},\"wordCount\":252,\"publisher\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\"},\"articleSection\":[\"Varie\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/\",\"name\":\"NESA e GESTIONI ELETTRONICHE presentano la SMTT presso il RESMA di Vigna di Valle - Nesa\",\"isPartOf\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\"},\"datePublished\":\"2014-09-17T10:47:00+00:00\",\"dateModified\":\"2023-03-01T08:31:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nesasrl.sp2.netkom.it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NESA e GESTIONI ELETTRONICHE presentano la SMTT presso il RESMA di Vigna di Valle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"name\":\"Nesa\",\"description\":\"Sistemi per il monitoraggio ambientale e telecontrollo\",\"publisher\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\",\"name\":\"Nesa srl\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"contentUrl\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"width\":264,\"height\":55,\"caption\":\"Nesa srl\"},\"image\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/nesa-srl\/\",\"https:\/\/www.facebook.com\/nesasrl\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/person\/f04f829b25d9803bd3039afd4b37395a\",\"name\":\"moris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f8a6da1a0980ff05aa322b98cbd1907117e072e21dd674cbce479e811160e614?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f8a6da1a0980ff05aa322b98cbd1907117e072e21dd674cbce479e811160e614?s=96&d=mm&r=g\",\"caption\":\"moris\"},\"sameAs\":[\"https:\/\/nesasrl.sp2.netkom.it\/\",\"https:\/\/twitter.com\/moris\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NESA e GESTIONI ELETTRONICHE presentano la SMTT presso il RESMA di Vigna di Valle - Nesa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nesasrl.sp2.netkom.it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/","og_locale":"en_US","og_type":"article","og_title":"NESA e GESTIONI ELETTRONICHE presentano la SMTT presso il RESMA di Vigna di Valle - Nesa","og_description":"Nesa SRL e Gestioni Elettroniche SPA nuovamente operativi presso Vigna di Valle sul lago di Bracciano (sede del\u00a0Reparto Sperimentazioni di Meteorologia Aeronautica,\u00a0ReSMA) con la presentazione della proposta di Stazione Meteorologica Trasportabile Tattica, a norma WMO, dotata di\u00a0sensoristica intelligente con protocollo seriale. La stazione si trasporta in massimo tre casse industriali di categoria ATA-300 e non &hellip; NESA e GESTIONI ELETTRONICHE presentano la SMTT presso il RESMA di Vigna di Valle Read More &raquo;","og_url":"https:\/\/nesasrl.sp2.netkom.it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/","og_site_name":"Nesa","article_publisher":"https:\/\/www.facebook.com\/nesasrl","article_published_time":"2014-09-17T10:47:00+00:00","article_modified_time":"2023-03-01T08:31:16+00:00","og_image":[{"width":640,"height":853,"url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/10\/vigna-di_valle_nesa2013_prew.jpg","type":"image\/jpeg"}],"author":"moris","twitter_card":"summary_large_image","twitter_creator":"@moris","twitter_misc":{"Written by":"moris","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nesasrl.sp2.netkom.it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/#article","isPartOf":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/"},"author":{"name":"moris","@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/person\/f04f829b25d9803bd3039afd4b37395a"},"headline":"NESA e GESTIONI ELETTRONICHE presentano la SMTT presso il RESMA di Vigna di Valle","datePublished":"2014-09-17T10:47:00+00:00","dateModified":"2023-03-01T08:31:16+00:00","mainEntityOfPage":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/"},"wordCount":252,"publisher":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization"},"articleSection":["Varie"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/nesasrl.sp2.netkom.it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/","url":"https:\/\/nesasrl.sp2.netkom.it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/","name":"NESA e GESTIONI ELETTRONICHE presentano la SMTT presso il RESMA di Vigna di Valle - Nesa","isPartOf":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#website"},"datePublished":"2014-09-17T10:47:00+00:00","dateModified":"2023-03-01T08:31:16+00:00","breadcrumb":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nesasrl.sp2.netkom.it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nesasrl.sp2.netkom.it\/nesa-e-gestioni-elettroniche-presentano-la-smtt-presso-il-resma-di-vigna-di-valle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nesasrl.sp2.netkom.it\/it\/"},{"@type":"ListItem","position":2,"name":"NESA e GESTIONI ELETTRONICHE presentano la SMTT presso il RESMA di Vigna di Valle"}]},{"@type":"WebSite","@id":"https:\/\/nesasrl.sp2.netkom.it\/#website","url":"https:\/\/nesasrl.sp2.netkom.it\/","name":"Nesa","description":"Sistemi per il monitoraggio ambientale e telecontrollo","publisher":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization","name":"Nesa srl","url":"https:\/\/nesasrl.sp2.netkom.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/","url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","contentUrl":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","width":264,"height":55,"caption":"Nesa srl"},"image":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/nesa-srl\/","https:\/\/www.facebook.com\/nesasrl"]},{"@type":"Person","@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/person\/f04f829b25d9803bd3039afd4b37395a","name":"moris","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f8a6da1a0980ff05aa322b98cbd1907117e072e21dd674cbce479e811160e614?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f8a6da1a0980ff05aa322b98cbd1907117e072e21dd674cbce479e811160e614?s=96&d=mm&r=g","caption":"moris"},"sameAs":["https:\/\/nesasrl.sp2.netkom.it\/","https:\/\/twitter.com\/moris"]}]}},"_links":{"self":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/posts\/3499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/comments?post=3499"}],"version-history":[{"count":1,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/posts\/3499\/revisions"}],"predecessor-version":[{"id":3504,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/posts\/3499\/revisions\/3504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/media\/3502"}],"wp:attachment":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/media?parent=3499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/categories?post=3499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/tags?post=3499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}