{"id":2440,"date":"2021-10-22T15:20:38","date_gmt":"2021-10-22T13:20:38","guid":{"rendered":"http:\/\/164.90.193.213\/?page_id=2440"},"modified":"2022-04-19T09:32:48","modified_gmt":"2022-04-19T07:32:48","slug":"pioggia-neve","status":"publish","type":"page","link":"https:\/\/nesasrl.sp2.netkom.it\/it\/strumenti\/sensori\/pioggia-neve\/","title":{"rendered":"Pioggia \/ Neve"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2440\" class=\"elementor elementor-2440\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d5041f6 elementor-section-full_width elementor-section-height-min-height elementor-section-items-top elementor-reverse-mobile elementor-section-height-default\" data-id=\"d5041f6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e9f040f\" data-id=\"e9f040f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb223cc elementor-widget elementor-widget-text-editor\" data-id=\"fb223cc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<h4><span style=\"color: #ffffff;\">Ampia gamma di pluviometri per la misura della pioggia e della precipitazione nevosa, tarati secondo le recenti norme\u00a0<\/span><span style=\"color: #ffffff;\">UNI 17277:2020<\/span><\/h4>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-669fa5a\" data-id=\"669fa5a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3607c2 elementor-widget elementor-widget-image\" data-id=\"c3607c2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1120\" height=\"520\" src=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/10\/strumenti-sensori-pioggia-neve_hero.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/10\/strumenti-sensori-pioggia-neve_hero.jpg 1120w, https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/10\/strumenti-sensori-pioggia-neve_hero-300x139.jpg 300w, https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/10\/strumenti-sensori-pioggia-neve_hero-1024x475.jpg 1024w, https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/10\/strumenti-sensori-pioggia-neve_hero-768x357.jpg 768w\" sizes=\"auto, (max-width: 1120px) 100vw, 1120px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-96d522c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"96d522c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-bca05d8\" data-id=\"bca05d8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31c1a94 elementor-widget elementor-widget-text-editor\" data-id=\"31c1a94\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h5>Pluviometri manuali, a bascula o a pesata, analogici e digitali.<\/h5><p>I sensori sono stati progettati e studiati\u00a0 in collaborazione con universit\u00e0 e centri di ricerca per soddisfare le linee guida del WMO (<span style=\"color: var(--ast-global-color-3); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size ); font-weight: var( --e-global-typography-text-font-weight );\">World Meteorological Organization) e le specifiche norme <strong>UNI 17277:2020<\/strong>. Corpo in alluminio anodizzato e verniciato bianco, sistemi a bascula a lama di coltello in acciaio inox 316, viterie inox,\u00a0 una garanzia di qualit\u00e0 della misura per lunghissimo tempo. Soluzioni con supporti specifici, da basamento, a muro o palo, disponibili con <strong>segnali di uscita On\/OFF, in tensione, corrente, o Modbus RS485<\/strong>.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3a05297\" data-id=\"3a05297\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c72f94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c72f94\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1117f51\" data-id=\"1117f51\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6693dd elementor-widget elementor-widget-heading\" data-id=\"e6693dd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">I nostri sensori installati <span class=\"colore-celeste\">in oltre migliaia di stazioni sparse nel mondo:<\/span><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eddb96b elementor-grid-eael-col-4 elementor-grid-tablet-eael-col-2 elementor-grid-mobile-eael-col-1 elementor-widget elementor-widget-eael-post-grid\" data-id=\"eddb96b\" data-element_type=\"widget\" data-settings=\"{&quot;eael_post_grid_columns&quot;:&quot;eael-col-4&quot;,&quot;eael_post_grid_columns_tablet&quot;:&quot;eael-col-2&quot;,&quot;eael_post_grid_columns_mobile&quot;:&quot;eael-col-1&quot;}\" data-widget_type=\"eael-post-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"eael-post-grid-eddb96b\" class=\"eael-post-grid-container\">\n            <div class=\"eael-post-grid eael-post-appender eael-post-appender-eddb96b eael-post-grid-style-default\" data-layout-mode=\"grid\"><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"5753\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"icon icon-arrow-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/nesasrl.sp2.netkom.it\/it\/prodotti\/pluviometro-classe-a-da-1000-cm%c2%b2-pl1000\/\"><\/a><\/div><div class=\"eael-entry-thumbnail \">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2022\/01\/strumenti-sensori-pioggia-neve_PL1000-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2022\/01\/strumenti-sensori-pioggia-neve_PL1000-300x300.jpg 300w, https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2022\/01\/strumenti-sensori-pioggia-neve_PL1000-150x150.jpg 150w, https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2022\/01\/strumenti-sensori-pioggia-neve_PL1000.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h3 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/nesasrl.sp2.netkom.it\/it\/prodotti\/pluviometro-classe-a-da-1000-cm%c2%b2-pl1000\/\"\n                        title=\"Pluviometro Classe A da 1000 cm\u00b2\">Pluviometro Classe A da 1000 cm\u00b2<\/a><\/h3><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>PL1000<\/p><\/div>\n                    <\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"5108\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"icon icon-arrow-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/nesasrl.sp2.netkom.it\/it\/prodotti\/pl400pluviometro-classe-a-da-400-cm%c2%b2-pl400\/\"><\/a><\/div><div class=\"eael-entry-thumbnail \">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"254\" src=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/12\/PL400-2-300x254.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/12\/PL400-2-300x254.jpg 300w, https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/12\/PL400-2-1024x866.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h3 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/nesasrl.sp2.netkom.it\/it\/prodotti\/pl400pluviometro-classe-a-da-400-cm%c2%b2-pl400\/\"\n                        title=\"Pluviometro Classe A da 400 cm\u00b2\">Pluviometro Classe A da 400 cm\u00b2<\/a><\/h3><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>PL400<\/p><\/div>\n                    <\/div><\/div><\/div>\n        <\/div>\n    <\/article><article class=\"eael-grid-post eael-post-grid-column\" data-id=\"5762\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"icon icon-arrow-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/nesasrl.sp2.netkom.it\/it\/prodotti\/pluviometro-classe-a-da-200-cm%c2%b2-pl200\/\"><\/a><\/div><div class=\"eael-entry-thumbnail \">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2022\/01\/Strumenti-sensori-pioggia-neve-PL200-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2022\/01\/Strumenti-sensori-pioggia-neve-PL200-300x300.jpg 300w, https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2022\/01\/Strumenti-sensori-pioggia-neve-PL200-150x150.jpg 150w, https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2022\/01\/Strumenti-sensori-pioggia-neve-PL200.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h3 class=\"eael-entry-title\"><a\n                        class=\"eael-grid-post-link\"\n                        href=\"https:\/\/nesasrl.sp2.netkom.it\/it\/prodotti\/pluviometro-classe-a-da-200-cm%c2%b2-pl200\/\"\n                        title=\"Pluviometro Classe A da 200 cm\u00b2\">Pluviometro Classe A da 200 cm\u00b2<\/a><\/h3><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><p>PL200<\/p><\/div>\n                    <\/div><\/div><\/div>\n        <\/div>\n    <\/article><\/div>\n            <div class=\"clearfix\"><\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3599023 bordo-nesa elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3599023\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a4f79b2\" data-id=\"a4f79b2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b1d79e elementor-widget elementor-widget-shortcode\" data-id=\"0b1d79e\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f6-o1\" lang=\"it-IT\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/2440#wpcf7-f6-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f6-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<div><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome e cognome*\" \/><\/span><\/div>\n<div><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email*\" \/><\/span><\/div>\n<div class=\"elementor-row\">\n<div class=\"nesa-row-sx form-positive\"><span class=\"wpcf7-form-control-wrap\" data-name=\"company\"><input type=\"text\" name=\"company\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Azienda*\" \/><\/span><\/div>\n<div class=\"nesa-row-dx form-positive\"><span class=\"wpcf7-form-control-wrap\" data-name=\"address\"><input type=\"text\" name=\"address\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Indirizzo\" \/><\/span><\/div>\n<\/div>\n<div class=\"elementor-row\">\n<div class=\"nesa-row-sx\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-city\"><input type=\"text\" name=\"your-city\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Citt\u00e0 \/ Provincia*\" \/><\/span><\/div>\n<div class=\"nesa-row-dx\"><span class=\"wpcf7-form-control-wrap\" data-name=\"phone\"><input type=\"tel\" name=\"phone\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Numero di telefono*\" \/><\/span><\/div>\n<\/div>\n<div><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Messaggio\"><\/textarea><\/span><\/div>\n<div class=\"privacy\">*campi obbligatori<\/div>\n<div class=\"privacy\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Ho letto la <a href=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/10\/INFORMATIVA-PRIVACY-NESA-IT.pdf\" target=\"_blank\">Privacy Policy<\/a> e acconsento al trattamento dei dati personali ai sensi del Regolamento UE n. 679\/2016.<\/span><\/label><\/span><\/span><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"newsletter\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"newsletter[]\" value=\"Iscrivimi alla newsletter.\" \/><span class=\"wpcf7-list-item-label\">Iscrivimi alla newsletter.<\/span><\/span><\/span><\/span>\n<\/div>\n<div style=\"text-align: right;\"><input type=\"submit\" value=\"INVIA\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/><\/div>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e9951e0\" data-id=\"e9951e0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4cc3c87 elementor-widget elementor-widget-text-editor\" data-id=\"4cc3c87\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>CONTATTACI<\/p><p>Siamo a tua disposizione per qualsiasi informazione, o chiamaci al<br \/><strong>+39 0423 985209<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ampia gamma di pluviometri per la misura della pioggia e della precipitazione nevosa, tarati secondo le recenti norme\u00a0UNI 17277:2020 Pluviometri manuali, a bascula o a pesata, analogici e digitali. I sensori sono stati progettati e studiati\u00a0 in collaborazione con universit\u00e0 e centri di ricerca per soddisfare le linee guida del WMO (World Meteorological Organization) e &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/nesasrl.sp2.netkom.it\/it\/prodotti\/pluviometro-classe-a-da-200-cm%c2%b2-pl200\/\"> <span class=\"screen-reader-text\">Pluviometro Classe A da 200 cm\u00b2<\/span> Read More &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1014,"menu_order":24,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"class_list":["post-2440","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pioggia \/ Neve - Nesa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nesasrl.sp2.netkom.it\/strumenti\/sensori\/pioggia-neve\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pioggia \/ Neve - Nesa\" \/>\n<meta property=\"og:description\" content=\"Ampia gamma di pluviometri per la misura della pioggia e della precipitazione nevosa, tarati secondo le recenti norme\u00a0UNI 17277:2020 Pluviometri manuali, a bascula o a pesata, analogici e digitali. I sensori sono stati progettati e studiati\u00a0 in collaborazione con universit\u00e0 e centri di ricerca per soddisfare le linee guida del WMO (World Meteorological Organization) e &hellip; Pluviometro Classe A da 200 cm\u00b2 Read More &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nesasrl.sp2.netkom.it\/strumenti\/sensori\/pioggia-neve\/\" \/>\n<meta property=\"og:site_name\" content=\"Nesa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nesasrl\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-19T07:32:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/10\/strumenti-sensori-pioggia-neve_hero.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/strumenti\/sensori\/pioggia-neve\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/strumenti\/sensori\/pioggia-neve\/\",\"name\":\"Pioggia \/ Neve - Nesa\",\"isPartOf\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\"},\"datePublished\":\"2021-10-22T13:20:38+00:00\",\"dateModified\":\"2022-04-19T07:32:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/strumenti\/sensori\/pioggia-neve\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nesasrl.sp2.netkom.it\/strumenti\/sensori\/pioggia-neve\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/strumenti\/sensori\/pioggia-neve\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/strumenti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sensori\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/strumenti\/sensori\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Pioggia \/ Neve\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"name\":\"Nesa\",\"description\":\"Sistemi per il monitoraggio ambientale e telecontrollo\",\"publisher\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\",\"name\":\"Nesa srl\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"contentUrl\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"width\":264,\"height\":55,\"caption\":\"Nesa srl\"},\"image\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/nesa-srl\/\",\"https:\/\/www.facebook.com\/nesasrl\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pioggia \/ Neve - Nesa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nesasrl.sp2.netkom.it\/strumenti\/sensori\/pioggia-neve\/","og_locale":"en_US","og_type":"article","og_title":"Pioggia \/ Neve - Nesa","og_description":"Ampia gamma di pluviometri per la misura della pioggia e della precipitazione nevosa, tarati secondo le recenti norme\u00a0UNI 17277:2020 Pluviometri manuali, a bascula o a pesata, analogici e digitali. I sensori sono stati progettati e studiati\u00a0 in collaborazione con universit\u00e0 e centri di ricerca per soddisfare le linee guida del WMO (World Meteorological Organization) e &hellip; Pluviometro Classe A da 200 cm\u00b2 Read More &raquo;","og_url":"https:\/\/nesasrl.sp2.netkom.it\/strumenti\/sensori\/pioggia-neve\/","og_site_name":"Nesa","article_publisher":"https:\/\/www.facebook.com\/nesasrl","article_modified_time":"2022-04-19T07:32:48+00:00","og_image":[{"url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/10\/strumenti-sensori-pioggia-neve_hero.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nesasrl.sp2.netkom.it\/strumenti\/sensori\/pioggia-neve\/","url":"https:\/\/nesasrl.sp2.netkom.it\/strumenti\/sensori\/pioggia-neve\/","name":"Pioggia \/ Neve - Nesa","isPartOf":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#website"},"datePublished":"2021-10-22T13:20:38+00:00","dateModified":"2022-04-19T07:32:48+00:00","breadcrumb":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/strumenti\/sensori\/pioggia-neve\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nesasrl.sp2.netkom.it\/strumenti\/sensori\/pioggia-neve\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nesasrl.sp2.netkom.it\/strumenti\/sensori\/pioggia-neve\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nesasrl.sp2.netkom.it\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/nesasrl.sp2.netkom.it\/strumenti\/"},{"@type":"ListItem","position":3,"name":"Sensori","item":"https:\/\/nesasrl.sp2.netkom.it\/strumenti\/sensori\/"},{"@type":"ListItem","position":4,"name":"Pioggia \/ Neve"}]},{"@type":"WebSite","@id":"https:\/\/nesasrl.sp2.netkom.it\/#website","url":"https:\/\/nesasrl.sp2.netkom.it\/","name":"Nesa","description":"Sistemi per il monitoraggio ambientale e telecontrollo","publisher":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization","name":"Nesa srl","url":"https:\/\/nesasrl.sp2.netkom.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/","url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","contentUrl":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","width":264,"height":55,"caption":"Nesa srl"},"image":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/nesa-srl\/","https:\/\/www.facebook.com\/nesasrl"]}]}},"_links":{"self":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/pages\/2440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/comments?post=2440"}],"version-history":[{"count":46,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/pages\/2440\/revisions"}],"predecessor-version":[{"id":13678,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/pages\/2440\/revisions\/13678"}],"up":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/pages\/1014"}],"wp:attachment":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/media?parent=2440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}