{"id":1405,"date":"2021-10-14T15:43:11","date_gmt":"2021-10-14T13:43:11","guid":{"rendered":"http:\/\/164.90.193.213\/?page_id=1405"},"modified":"2022-05-05T13:08:44","modified_gmt":"2022-05-05T11:08:44","slug":"aria-strade-e-gas","status":"publish","type":"page","link":"https:\/\/nesasrl.sp2.netkom.it\/it\/sistemi\/aria-strade-e-gas\/","title":{"rendered":"Aria, strade e gas"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1405\" class=\"elementor elementor-1405\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ea165e1 elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"ea165e1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8910db2\" data-id=\"8910db2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-87b2b62 elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"87b2b62\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2aff802\" data-id=\"2aff802\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb9d629 elementor-widget elementor-widget-spacer\" data-id=\"fb9d629\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.e-container.e-container--row .elementor-spacer-inner{width:var(--spacer-size)}.e-container.e-container--column .elementor-spacer-inner,.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b2e58fd\" data-id=\"b2e58fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e34d551 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"e34d551\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-660a027\" data-id=\"660a027\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ed1ff0 elementor-widget elementor-widget-text-editor\" data-id=\"0ed1ff0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Una gamma di soluzioni completa per il monitoraggio dei <span style=\"color: #0075be;\">gas inquinanti<\/span><span style=\"color: #00ccff;\"> \u00a0<\/span>e delle <span style=\"color: #0075be;\">condizioni meteoclimatiche <span style=\"color: #000000;\">e delle<\/span> polveri <\/span>lungo le strade.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-65cd1f6\" data-id=\"65cd1f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51a66a4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"51a66a4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-3dc2253\" data-id=\"3dc2253\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-470dda2 elementor-widget elementor-widget-text-editor\" data-id=\"470dda2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h5>Soluzioni professionali scalabili per ogni esigenza<\/h5><p>Sistemi e stazioni professionali per la misura delle concentrazioni GAS e delle condizioni delle strade e dell&#8217;aria circostante, ai fini del benessere, della sicurezza o per capire quali siano le condizioni della superficie dell&#8217;asfalto. Dalla semplice misura di temperatura che si installa in pochi minuti e consente di avere gi\u00e0 la misura on line, a sistemi complessi che analizzano lo spessore dello strato d&#8217;acqua\/neve, la salinit\u00e0, i tipi di gas, le polveri. Soluzioni tradizionali con datalogger e soluzioni IoT particolarmente performanti.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dfbcec9\" data-id=\"dfbcec9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f87d5a colonne-sensori elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f87d5a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-746a08e\" data-id=\"746a08e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c2c4d00 elementor-section-content-space-evenly elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c2c4d00\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-dec1e12\" data-id=\"dec1e12\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1476a5e ekit-equal-height-enable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"1476a5e\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/sistema-monitoraggio-stradale-st-strade\/\" target=\"_self\" rel=\"\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text- icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1\" data-name=\"Livello 1\" viewBox=\"0 0 300 300\"><defs><style>.cls-1{fill:#728895;}<\/style><\/defs><path class=\"cls-1\" d=\"M150,267.1a1,1,0,0,1-1-1v-50a1,1,0,0,1,2,0v50A1,1,0,0,1,150,267.1Z\"><\/path><path class=\"cls-1\" d=\"M150,79.07a1,1,0,0,1-1-1v-20a1,1,0,1,1,2,0v20A1,1,0,0,1,150,79.07Z\"><\/path><path class=\"cls-1\" d=\"M150,44.9a1,1,0,0,1-1-1v-10a1,1,0,0,1,2,0v10A1,1,0,0,1,150,44.9Z\"><\/path><path class=\"cls-1\" d=\"M150,146.76a1,1,0,0,0-1,1v40a1,1,0,0,0,2,0v-40A1,1,0,0,0,150,146.76Z\"><\/path><path class=\"cls-1\" d=\"M150,94.08a1,1,0,0,0-1,1v30a1,1,0,0,0,2,0v-30A1,1,0,0,0,150,94.08Z\"><\/path><rect class=\"cls-1\" x=\"200.94\" y=\"32.44\" width=\"3\" height=\"235.11\" transform=\"translate(-21.03 33.62) rotate(-9.03)\"><\/rect><rect class=\"cls-1\" x=\"-20\" y=\"148.5\" width=\"235.11\" height=\"3\" transform=\"translate(-65.89 222.82) rotate(-80.97)\"><\/rect><\/svg>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h2 class=\"elementskit-info-box-title\">\n                    Strade                <\/h2>\n                                            <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-dd7b44b\" data-id=\"dd7b44b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec4ed8a ekit-equal-height-enable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"ec4ed8a\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/aria-strade-e-gas\/aria-e-gas\/\" target=\"_self\" rel=\"\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text- icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1\" data-name=\"Livello 1\" viewBox=\"0 0 300 300\"><defs><style>.cls-1{fill:#728895;}<\/style><\/defs><path class=\"cls-1\" d=\"M187.72,204.91a1.56,1.56,0,0,1-1.16-.53,1.53,1.53,0,0,1,.13-2.16c8.31-7.38,19.47-22.91,25.31-54.84a1.54,1.54,0,0,1,1.78-1.25,1.56,1.56,0,0,1,1.25,1.78c-6,32.81-17.62,48.87-26.31,56.59A1.38,1.38,0,0,1,187.72,204.91Z\"><\/path><path class=\"cls-1\" d=\"M112.28,204.91a1.62,1.62,0,0,1-1-.38c-8.69-7.72-20.31-23.78-26.31-56.59a1.51,1.51,0,0,1,1.25-1.78A1.54,1.54,0,0,1,88,147.41c5.84,31.93,17,47.47,25.31,54.84a1.53,1.53,0,0,1,.13,2.16A1.43,1.43,0,0,1,112.28,204.91Z\"><\/path><path class=\"cls-1\" d=\"M214.62,101.41a1.56,1.56,0,0,1-1.53-1.32,59.12,59.12,0,0,0-17.53-29.28,67.39,67.39,0,0,0-91.15,0,59.45,59.45,0,0,0-17.53,29.32,1.48,1.48,0,0,1-.38.68,1.57,1.57,0,0,1-2.19.07A1.5,1.5,0,0,1,84,99.16a62.21,62.21,0,0,1,18.37-30.6,70.47,70.47,0,0,1,95.32,0,61.91,61.91,0,0,1,18.43,30.91,1.61,1.61,0,0,1,.07.37A1.57,1.57,0,0,1,214.62,101.41Z\"><\/path><path class=\"cls-1\" d=\"M150,230.28A29.25,29.25,0,1,1,179.25,201,29.28,29.28,0,0,1,150,230.28Zm0-55.41A26.16,26.16,0,1,0,176.16,201,26.19,26.19,0,0,0,150,174.87Z\"><\/path><path class=\"cls-1\" d=\"M150,240.34A39.33,39.33,0,1,1,189.34,201,39.39,39.39,0,0,1,150,240.34Zm0-75.56A36.25,36.25,0,1,0,186.25,201,36.28,36.28,0,0,0,150,164.78Z\"><\/path><path class=\"cls-1\" d=\"M213.09,250a4.64,4.64,0,0,1-2.31-.63l-17.31-10a4.64,4.64,0,0,1-1.69-6.34L212,198.09a4.64,4.64,0,0,1,6.34-1.68l17.31,10a4.64,4.64,0,0,1,1.69,6.34h0l-20.19,34.94a4.61,4.61,0,0,1-2.81,2.15A5,5,0,0,1,213.09,250ZM216,198.84a1.47,1.47,0,0,0-.41.07,1.6,1.6,0,0,0-1,.72l-20.18,34.93a1.58,1.58,0,0,0,.56,2.16l17.31,10a1.43,1.43,0,0,0,1.19.15,1.59,1.59,0,0,0,1-.71l20.19-34.94h0a1.59,1.59,0,0,0-.57-2.16l-17.31-10A1.46,1.46,0,0,0,216,198.84ZM236,212Z\"><\/path><path class=\"cls-1\" d=\"M209.91,206.28a1.48,1.48,0,0,1-.79-.22l-15.28-8.81a1.53,1.53,0,0,1,1.53-2.66l15.29,8.82a1.5,1.5,0,0,1,.56,2.09A1.46,1.46,0,0,1,209.91,206.28Z\"><\/path><path class=\"cls-1\" d=\"M196.53,229.44a1.54,1.54,0,0,1-.78-.22l-13.81-8a1.53,1.53,0,1,1,1.53-2.66l13.81,8a1.52,1.52,0,0,1,.56,2.1A1.44,1.44,0,0,1,196.53,229.44Z\"><\/path><path class=\"cls-1\" d=\"M206.53,246.69a1.54,1.54,0,0,1-.78-.22,1.51,1.51,0,0,1-.56-2.09l23.31-40.32a1.56,1.56,0,0,1,2.09-.56,1.52,1.52,0,0,1,.57,2.09l-23.32,40.32A1.46,1.46,0,0,1,206.53,246.69Z\"><\/path><path class=\"cls-1\" d=\"M86.91,250a5,5,0,0,1-1.22-.16,4.61,4.61,0,0,1-2.81-2.15L62.69,212.75h0a4.63,4.63,0,0,1,1.69-6.34l17.31-10A4.64,4.64,0,0,1,88,198.09L108.22,233a4.63,4.63,0,0,1-1.69,6.34l-17.31,10A4.64,4.64,0,0,1,86.91,250ZM65.34,211.22l20.19,34.94a1.49,1.49,0,0,0,1,.71,1.55,1.55,0,0,0,1.19-.15l17.31-10a1.58,1.58,0,0,0,.56-2.16L85.38,199.63a1.49,1.49,0,0,0-1-.72,1.55,1.55,0,0,0-1.19.15l-17.31,10a1.59,1.59,0,0,0-.57,2.16Z\"><\/path><path class=\"cls-1\" d=\"M90.09,206.28a1.58,1.58,0,0,1-1.34-.78,1.49,1.49,0,0,1,.56-2.09l15.25-8.85a1.52,1.52,0,0,1,2.1.57,1.5,1.5,0,0,1-.57,2.09l-15.25,8.84A1.27,1.27,0,0,1,90.09,206.28Z\"><\/path><path class=\"cls-1\" d=\"M103.47,229.44a1.54,1.54,0,0,1-1.34-.78,1.5,1.5,0,0,1,.56-2.1l13.81-8a1.53,1.53,0,0,1,1.53,2.66l-13.81,8A1.23,1.23,0,0,1,103.47,229.44Z\"><\/path><path class=\"cls-1\" d=\"M93.47,246.69a1.58,1.58,0,0,1-1.34-.78L68.81,205.59a1.53,1.53,0,0,1,2.66-1.53l23.31,40.32a1.49,1.49,0,0,1-.56,2.09A1.36,1.36,0,0,1,93.47,246.69Z\"><\/path><path class=\"cls-1\" d=\"M192,156.69c-22.16-.07-35.47-12.25-42-20.57-6.56,8.35-19.88,20.5-41.91,20.57-9.84,0-17.34-2.53-22.34-7.57-7.44-7.4-7.44-17.78-7.41-24.65v-2.16c-.15-8.09.54-18.22,7.07-24.75,3.81-3.81,9.06-5.78,15.43-5.62h98.47c6.28-.13,11.47,1.75,15.38,5.62h0c6.53,6.53,7.22,16.66,7.06,24.75v2.16c0,6.87,0,17.25-7.41,24.65C209.25,154.12,201.75,156.69,192,156.69ZM150,132a1.57,1.57,0,0,1,1.25.63c5.69,7.81,18.5,20.9,40.66,20.93,9,0,15.75-2.25,20.18-6.65,6.53-6.5,6.53-16.1,6.53-22.47v-2.22c.13-7.5-.43-16.81-6.15-22.53h0c-3.25-3.25-7.69-4.84-13.16-4.72H100.78c-5.56-.16-10,1.47-13.22,4.72-5.72,5.72-6.31,15-6.15,22.53v2.22c0,6.34,0,16,6.53,22.47,4.4,4.4,11.15,6.65,20.06,6.65a49.61,49.61,0,0,0,40.78-20.93A1.4,1.4,0,0,1,150,132Zm-42.34,16.13c-7.1,0-12.6-1.75-15.91-5.07-4.94-4.9-4.91-12.84-4.91-18.62v-2.31c-.09-5.91.25-14.25,4.57-18.57,2.09-2.09,5-3.12,8.84-3.12h99.12c4.13,0,7.1,1,9.25,3.12,4.32,4.32,4.66,12.66,4.57,18.57h0v2.31c0,5.78,0,13.69-4.91,18.59-3.37,3.35-8.81,5.06-16.22,5.06-27.75-.06-39.09-22.84-39.56-23.81a2.83,2.83,0,0,0-4.91,0c-.09.22-11.5,23.75-39.46,23.81A2,2,0,0,1,107.66,148.16Zm-7.44-44.6c-3,0-5.16.72-6.66,2.22-3.87,3.88-3.72,13.25-3.65,16.34v2.35c0,5.25,0,12.4,4,16.44,2.78,2.78,7.81,4.21,14.12,4.15,25.78-.06,36.6-21.84,36.72-22.06a5.84,5.84,0,0,1,5.22-3.31,5.76,5.76,0,0,1,5.22,3.31c.44.91,11,22,36.69,22.06,6.65,0,11.37-1.4,14.12-4.15,4-4,4-11.19,4-16.41v-2.38h0c.1-5.34-.19-12.87-3.65-16.34-1.57-1.56-3.72-2.28-7.07-2.22H100.22Z\"><\/path><\/svg>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h2 class=\"elementskit-info-box-title\">\n                    Aria e gas                <\/h2>\n                                            <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c76e952\" data-id=\"c76e952\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b296aa0 bordo-nesa elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b296aa0\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-831f5ea\" data-id=\"831f5ea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d470234 elementor-widget elementor-widget-shortcode\" data-id=\"d470234\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f6-o1\" lang=\"it-IT\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/1405#wpcf7-f6-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f6-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<div><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome e cognome*\" \/><\/span><\/div>\n<div><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email*\" \/><\/span><\/div>\n<div class=\"elementor-row\">\n<div class=\"nesa-row-sx form-positive\"><span class=\"wpcf7-form-control-wrap\" data-name=\"company\"><input type=\"text\" name=\"company\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Azienda*\" \/><\/span><\/div>\n<div class=\"nesa-row-dx form-positive\"><span class=\"wpcf7-form-control-wrap\" data-name=\"address\"><input type=\"text\" name=\"address\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Indirizzo\" \/><\/span><\/div>\n<\/div>\n<div class=\"elementor-row\">\n<div class=\"nesa-row-sx\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-city\"><input type=\"text\" name=\"your-city\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Citt\u00e0 \/ Provincia*\" \/><\/span><\/div>\n<div class=\"nesa-row-dx\"><span class=\"wpcf7-form-control-wrap\" data-name=\"phone\"><input type=\"tel\" name=\"phone\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Numero di telefono*\" \/><\/span><\/div>\n<\/div>\n<div><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Messaggio\"><\/textarea><\/span><\/div>\n<div class=\"privacy\">*campi obbligatori<\/div>\n<div class=\"privacy\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Ho letto la <a href=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/10\/INFORMATIVA-PRIVACY-NESA-IT.pdf\" target=\"_blank\">Privacy Policy<\/a> e acconsento al trattamento dei dati personali ai sensi del Regolamento UE n. 679\/2016.<\/span><\/label><\/span><\/span><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"newsletter\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"newsletter[]\" value=\"Iscrivimi alla newsletter.\" \/><span class=\"wpcf7-list-item-label\">Iscrivimi alla newsletter.<\/span><\/span><\/span><\/span>\n<\/div>\n<div style=\"text-align: right;\"><input type=\"submit\" value=\"INVIA\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/><\/div>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f970ed9\" data-id=\"f970ed9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cdadfa5 elementor-widget elementor-widget-text-editor\" data-id=\"cdadfa5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>CONTATTACI<\/p><p><span style=\"font-style: inherit; font-weight: inherit; font-family: var( --e-global-typography-text-font-family ), Sans-serif; background-color: var( --e-global-color-astglobalcolor0 );\">Siamo a tua disposizione per qualsiasi informazione, o chiamaci al<\/span><\/p><p>\n<strong>+39 0423 985209<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Una gamma di soluzioni completa per il monitoraggio dei gas inquinanti \u00a0e delle condizioni meteoclimatiche e delle polveri lungo le strade. Soluzioni professionali scalabili per ogni esigenza Sistemi e stazioni professionali per la misura delle concentrazioni GAS e delle condizioni delle strade e dell&#8217;aria circostante, ai fini del benessere, della sicurezza o per capire quali &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/nesasrl.sp2.netkom.it\/it\/sistemi\/aria-strade-e-gas\/\"> <span class=\"screen-reader-text\">Aria, strade e gas<\/span> Read More &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":131,"menu_order":51,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"class_list":["post-1405","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aria, strade e gas - Nesa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/aria-strade-e-gas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aria, strade e gas - Nesa\" \/>\n<meta property=\"og:description\" content=\"Una gamma di soluzioni completa per il monitoraggio dei gas inquinanti \u00a0e delle condizioni meteoclimatiche e delle polveri lungo le strade. Soluzioni professionali scalabili per ogni esigenza Sistemi e stazioni professionali per la misura delle concentrazioni GAS e delle condizioni delle strade e dell&#8217;aria circostante, ai fini del benessere, della sicurezza o per capire quali &hellip; Aria, strade e gas Read More &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/aria-strade-e-gas\/\" \/>\n<meta property=\"og:site_name\" content=\"Nesa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nesasrl\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-05T11:08:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/nesa_slide-home-mountain-bg5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/aria-strade-e-gas\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/aria-strade-e-gas\/\",\"name\":\"Aria, strade e gas - Nesa\",\"isPartOf\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\"},\"datePublished\":\"2021-10-14T13:43:11+00:00\",\"dateModified\":\"2022-05-05T11:08:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/aria-strade-e-gas\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/aria-strade-e-gas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/aria-strade-e-gas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sistemi\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aria, strade e gas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"name\":\"Nesa\",\"description\":\"Sistemi per il monitoraggio ambientale e telecontrollo\",\"publisher\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\",\"name\":\"Nesa srl\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"contentUrl\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"width\":264,\"height\":55,\"caption\":\"Nesa srl\"},\"image\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/nesa-srl\/\",\"https:\/\/www.facebook.com\/nesasrl\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aria, strade e gas - Nesa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/aria-strade-e-gas\/","og_locale":"en_US","og_type":"article","og_title":"Aria, strade e gas - Nesa","og_description":"Una gamma di soluzioni completa per il monitoraggio dei gas inquinanti \u00a0e delle condizioni meteoclimatiche e delle polveri lungo le strade. Soluzioni professionali scalabili per ogni esigenza Sistemi e stazioni professionali per la misura delle concentrazioni GAS e delle condizioni delle strade e dell&#8217;aria circostante, ai fini del benessere, della sicurezza o per capire quali &hellip; Aria, strade e gas Read More &raquo;","og_url":"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/aria-strade-e-gas\/","og_site_name":"Nesa","article_publisher":"https:\/\/www.facebook.com\/nesasrl","article_modified_time":"2022-05-05T11:08:44+00:00","og_image":[{"width":1920,"height":900,"url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/nesa_slide-home-mountain-bg5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/aria-strade-e-gas\/","url":"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/aria-strade-e-gas\/","name":"Aria, strade e gas - Nesa","isPartOf":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#website"},"datePublished":"2021-10-14T13:43:11+00:00","dateModified":"2022-05-05T11:08:44+00:00","breadcrumb":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/aria-strade-e-gas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nesasrl.sp2.netkom.it\/sistemi\/aria-strade-e-gas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/aria-strade-e-gas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nesasrl.sp2.netkom.it\/it\/"},{"@type":"ListItem","position":2,"name":"Sistemi","item":"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/"},{"@type":"ListItem","position":3,"name":"Aria, strade e gas"}]},{"@type":"WebSite","@id":"https:\/\/nesasrl.sp2.netkom.it\/#website","url":"https:\/\/nesasrl.sp2.netkom.it\/","name":"Nesa","description":"Sistemi per il monitoraggio ambientale e telecontrollo","publisher":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization","name":"Nesa srl","url":"https:\/\/nesasrl.sp2.netkom.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/","url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","contentUrl":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","width":264,"height":55,"caption":"Nesa srl"},"image":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/nesa-srl\/","https:\/\/www.facebook.com\/nesasrl"]}]}},"_links":{"self":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/pages\/1405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/comments?post=1405"}],"version-history":[{"count":60,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/pages\/1405\/revisions"}],"predecessor-version":[{"id":14534,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/pages\/1405\/revisions\/14534"}],"up":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/pages\/131"}],"wp:attachment":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/media?parent=1405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}