{"id":1401,"date":"2021-10-14T15:38:35","date_gmt":"2021-10-14T13:38:35","guid":{"rendered":"http:\/\/164.90.193.213\/?page_id=1401"},"modified":"2022-05-05T13:08:02","modified_gmt":"2022-05-05T11:08:02","slug":"idrologico","status":"publish","type":"page","link":"https:\/\/nesasrl.sp2.netkom.it\/it\/sistemi\/idrologico\/","title":{"rendered":"Idrologico"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1401\" class=\"elementor elementor-1401\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ea165e1 elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"ea165e1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8910db2\" data-id=\"8910db2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-87b2b62 elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"87b2b62\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2aff802\" data-id=\"2aff802\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb9d629 elementor-widget elementor-widget-spacer\" data-id=\"fb9d629\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.e-container.e-container--row .elementor-spacer-inner{width:var(--spacer-size)}.e-container.e-container--column .elementor-spacer-inner,.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b2e58fd\" data-id=\"b2e58fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e34d551 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"e34d551\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-660a027\" data-id=\"660a027\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ed1ff0 elementor-widget elementor-widget-text-editor\" data-id=\"0ed1ff0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Sistemi per il controllo dei <span style=\"color: #0075be;\">livelli<\/span>, della <span style=\"color: #0075be;\">qualit\u00e0 delle acque<\/span> e <span style=\"color: #0075be;\">sistemi di allertamento per il rischio idrogeologico<\/span>, con le migliori tecnologie.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-65cd1f6\" data-id=\"65cd1f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51a66a4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"51a66a4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-3dc2253\" data-id=\"3dc2253\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-470dda2 elementor-widget elementor-widget-text-editor\" data-id=\"470dda2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h5>Stazioni professionali realizzate ai fini della misura e del controllo del rischio idrico: piogge, esondazioni, piene, fenomeni torrentizi, qualit\u00e0 dell&#8217;acqua ecc.<\/h5><p>Le nostre soluzioni sono modulari e flessibili, di tipo tradizionale con datalogger, o di ultima generazione con tecnologia IoT. Sviluppate per una facile installazione, anche in zone critiche, per un immediato utilizzo, altamente performanti, con costi e oneri di gestione contenuti.<br \/>Le stazioni sono predisposte per l\u2019invio di dati e allarmi in cloud e tramite APP (<strong>NESA Sunflower<\/strong>) e l\u2019attivazione in locale di eventuali comandi per sirene o lampade. Possono essere integrate con telecamere per un ulteriore controllo visivo.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dfbcec9\" data-id=\"dfbcec9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f87d5a colonne-sensori elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f87d5a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-746a08e\" data-id=\"746a08e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c2c4d00 elementor-section-content-space-evenly elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c2c4d00\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-dec1e12\" data-id=\"dec1e12\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1476a5e ekit-equal-height-enable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"1476a5e\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"https:\/\/nesasrl.sp2.netkom.it\/prodotti\/sistema-monitoraggio-rischio-idrologico-stn-idro\/\" target=\"_self\" rel=\"\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text- icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1\" data-name=\"Livello 1\" viewBox=\"0 0 300 300\"><defs><style>.cls-1{fill:#728895;}<\/style><\/defs><path class=\"cls-1\" d=\"M173.25,235.65H126.76c-41.19,0-58.15-41.1-71.77-74.11-8.41-20.39-15.67-38-26.16-38v-2.5c12.16,0,19.36,17.44,28.47,39.53,13.34,32.33,29.94,72.57,69.46,72.57h46.49c39.51,0,56.11-40.24,69.45-72.57,9.11-22.09,16.31-39.53,28.47-39.53v2.5c-10.49,0-17.75,17.6-26.16,38C231.39,194.55,214.43,235.65,173.25,235.65Z\"><\/path><path class=\"cls-1\" d=\"M212.76,134.34l.64,1a14.07,14.07,0,0,0,11.92,6.45,13.87,13.87,0,0,0,14.06-13.64,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.5,1.5,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.5,1.5,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,13.87,13.87,0,0,0,14.06,13.64,14.07,14.07,0,0,0,11.92-6.45l.63-1,.64,1a14.24,14.24,0,0,0,23.84,0l.63-1,.63,1a14.25,14.25,0,0,0,23.85,0l.63-1,.63,1a14.24,14.24,0,0,0,23.84,0l.63-1,.63,1a14.25,14.25,0,0,0,23.85,0l.63-1,.63,1a14.24,14.24,0,0,0,23.84,0Z\"><\/path><path class=\"cls-1\" d=\"M200.21,158.56l.63,1A14.1,14.1,0,0,0,212.77,166a13.86,13.86,0,0,0,14-13.64,1.51,1.51,0,0,0-3,0,11.05,11.05,0,0,1-22.09,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.5,1.5,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.05,11.05,0,0,1-22.09,0,1.51,1.51,0,0,0-3,0,13.86,13.86,0,0,0,14,13.64,14.1,14.1,0,0,0,11.93-6.45l.63-1,.63,1a14.24,14.24,0,0,0,23.84,0l.63-1,.63,1a14.25,14.25,0,0,0,23.85,0l.63-1,.63,1a14.25,14.25,0,0,0,23.85,0l.63-1,.63,1a14.24,14.24,0,0,0,23.84,0Z\"><\/path><path class=\"cls-1\" d=\"M150,218a1.25,1.25,0,0,1-1.25-1.25V190.34a1.25,1.25,0,0,1,2.5,0v26.44A1.25,1.25,0,0,1,150,218Z\"><\/path><polygon class=\"cls-1\" points=\"137.85 191.97 162.15 191.97 150 179.83 137.85 191.97\"><\/polygon><\/svg>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h2 class=\"elementskit-info-box-title\">\n                    Idrologico                <\/h2>\n                                            <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-dd7b44b\" data-id=\"dd7b44b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec4ed8a ekit-equal-height-enable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"ec4ed8a\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/idrologico\/qualita-delle-acque\/\" target=\"_self\" rel=\"\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text- icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1\" data-name=\"Livello 1\" viewBox=\"0 0 300 300\"><defs><style>.cls-1{fill:#728895;}<\/style><\/defs><path class=\"cls-1\" d=\"M212.76,178.35l.64,1a14.08,14.08,0,0,0,11.92,6.46,13.87,13.87,0,0,0,14.06-13.65,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.5,1.5,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.5,1.5,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,13.87,13.87,0,0,0,14.06,13.65,14.08,14.08,0,0,0,11.92-6.46l.63-1,.64,1a14.23,14.23,0,0,0,23.84,0l.63-1,.63,1a14.24,14.24,0,0,0,23.85,0l.63-1,.63,1a14.23,14.23,0,0,0,23.84,0l.63-1,.63,1a14.24,14.24,0,0,0,23.85,0l.63-1,.63,1a14.23,14.23,0,0,0,23.84,0Z\"><\/path><path class=\"cls-1\" d=\"M212.76,206.57l.64,1A14.07,14.07,0,0,0,225.32,214a13.87,13.87,0,0,0,14.06-13.64,1.51,1.51,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.5,1.5,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.5,1.5,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,1,0-3,0A13.87,13.87,0,0,0,74.68,214a14.07,14.07,0,0,0,11.92-6.45l.63-1,.64,1a14.24,14.24,0,0,0,23.84,0l.63-1,.63,1a14.25,14.25,0,0,0,23.85,0l.63-1,.63,1a14.24,14.24,0,0,0,23.84,0l.63-1,.63,1a14.25,14.25,0,0,0,23.85,0l.63-1,.63,1a14.24,14.24,0,0,0,23.84,0Z\"><\/path><path class=\"cls-1\" d=\"M212.76,121.92l.64,1a14.07,14.07,0,0,0,11.92,6.45,13.87,13.87,0,0,0,14.06-13.64,1.51,1.51,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.5,1.5,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.5,1.5,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,1,0-3,0,13.87,13.87,0,0,0,14.06,13.64,14.07,14.07,0,0,0,11.92-6.45l.63-1,.64,1a14.24,14.24,0,0,0,23.84,0l.63-1,.63,1a14.25,14.25,0,0,0,23.85,0l.63-1,.63,1a14.24,14.24,0,0,0,23.84,0l.63-1,.63,1a14.25,14.25,0,0,0,23.85,0l.63-1,.63,1a14.24,14.24,0,0,0,23.84,0Z\"><\/path><path class=\"cls-1\" d=\"M212.76,150.14l.64,1a14.07,14.07,0,0,0,11.92,6.45,13.87,13.87,0,0,0,14.06-13.64,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.5,1.5,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.5,1.5,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,13.87,13.87,0,0,0,14.06,13.64,14.07,14.07,0,0,0,11.92-6.45l.63-1,.64,1a14.24,14.24,0,0,0,23.84,0l.63-1,.63,1a14.25,14.25,0,0,0,23.85,0l.63-1,.63,1a14.24,14.24,0,0,0,23.84,0l.63-1,.63,1a14.25,14.25,0,0,0,23.85,0l.63-1,.63,1a14.24,14.24,0,0,0,23.84,0Z\"><\/path><path class=\"cls-1\" d=\"M212.76,93.71l.64,1a14.08,14.08,0,0,0,11.92,6.46A13.87,13.87,0,0,0,239.38,87.5a1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.5,1.5,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.5,1.5,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,13.87,13.87,0,0,0,14.06,13.65A14.08,14.08,0,0,0,86.6,94.69l.63-1,.64,1a14.23,14.23,0,0,0,23.84,0l.63-1,.63,1a14.24,14.24,0,0,0,23.85,0l.63-1,.63,1a14.23,14.23,0,0,0,23.84,0l.63-1,.63,1a14.24,14.24,0,0,0,23.85,0l.63-1,.63,1a14.23,14.23,0,0,0,23.84,0Z\"><\/path><\/svg>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h2 class=\"elementskit-info-box-title\">\n                    Qualit\u00e0 delle acque                <\/h2>\n                                            <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c76e952\" data-id=\"c76e952\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b296aa0 bordo-nesa elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b296aa0\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-831f5ea\" data-id=\"831f5ea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d470234 elementor-widget elementor-widget-shortcode\" data-id=\"d470234\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f6-o1\" lang=\"it-IT\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/1401#wpcf7-f6-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f6-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<div><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome e cognome*\" \/><\/span><\/div>\n<div><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email*\" \/><\/span><\/div>\n<div class=\"elementor-row\">\n<div class=\"nesa-row-sx form-positive\"><span class=\"wpcf7-form-control-wrap\" data-name=\"company\"><input type=\"text\" name=\"company\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Azienda*\" \/><\/span><\/div>\n<div class=\"nesa-row-dx form-positive\"><span class=\"wpcf7-form-control-wrap\" data-name=\"address\"><input type=\"text\" name=\"address\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Indirizzo\" \/><\/span><\/div>\n<\/div>\n<div class=\"elementor-row\">\n<div class=\"nesa-row-sx\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-city\"><input type=\"text\" name=\"your-city\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Citt\u00e0 \/ Provincia*\" \/><\/span><\/div>\n<div class=\"nesa-row-dx\"><span class=\"wpcf7-form-control-wrap\" data-name=\"phone\"><input type=\"tel\" name=\"phone\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Numero di telefono*\" \/><\/span><\/div>\n<\/div>\n<div><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Messaggio\"><\/textarea><\/span><\/div>\n<div class=\"privacy\">*campi obbligatori<\/div>\n<div class=\"privacy\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Ho letto la <a href=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/10\/INFORMATIVA-PRIVACY-NESA-IT.pdf\" target=\"_blank\">Privacy Policy<\/a> e acconsento al trattamento dei dati personali ai sensi del Regolamento UE n. 679\/2016.<\/span><\/label><\/span><\/span><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"newsletter\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"newsletter[]\" value=\"Iscrivimi alla newsletter.\" \/><span class=\"wpcf7-list-item-label\">Iscrivimi alla newsletter.<\/span><\/span><\/span><\/span>\n<\/div>\n<div style=\"text-align: right;\"><input type=\"submit\" value=\"INVIA\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/><\/div>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f970ed9\" data-id=\"f970ed9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cdadfa5 elementor-widget elementor-widget-text-editor\" data-id=\"cdadfa5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>CONTATTACI<\/p><p>Siamo a tua disposizione per qualsiasi informazione, o chiamaci al<br>\n<strong>+39 0423 985209<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sistemi per il controllo dei livelli, della qualit\u00e0 delle acque e sistemi di allertamento per il rischio idrogeologico, con le migliori tecnologie. Stazioni professionali realizzate ai fini della misura e del controllo del rischio idrico: piogge, esondazioni, piene, fenomeni torrentizi, qualit\u00e0 dell&#8217;acqua ecc. Le nostre soluzioni sono modulari e flessibili, di tipo tradizionale con datalogger, &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/nesasrl.sp2.netkom.it\/it\/sistemi\/idrologico\/\"> <span class=\"screen-reader-text\">Idrologico<\/span> Read More &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":131,"menu_order":52,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"class_list":["post-1401","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Idrologico - Nesa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/idrologico\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Idrologico - Nesa\" \/>\n<meta property=\"og:description\" content=\"Sistemi per il controllo dei livelli, della qualit\u00e0 delle acque e sistemi di allertamento per il rischio idrogeologico, con le migliori tecnologie. Stazioni professionali realizzate ai fini della misura e del controllo del rischio idrico: piogge, esondazioni, piene, fenomeni torrentizi, qualit\u00e0 dell&#8217;acqua ecc. Le nostre soluzioni sono modulari e flessibili, di tipo tradizionale con datalogger, &hellip; Idrologico Read More &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/idrologico\/\" \/>\n<meta property=\"og:site_name\" content=\"Nesa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nesasrl\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-05T11:08:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/nesa_slide-home-mountain-bg5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/idrologico\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/idrologico\/\",\"name\":\"Idrologico - Nesa\",\"isPartOf\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\"},\"datePublished\":\"2021-10-14T13:38:35+00:00\",\"dateModified\":\"2022-05-05T11:08:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/idrologico\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/idrologico\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/idrologico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sistemi\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Idrologico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"name\":\"Nesa\",\"description\":\"Sistemi per il monitoraggio ambientale e telecontrollo\",\"publisher\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\",\"name\":\"Nesa srl\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"contentUrl\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"width\":264,\"height\":55,\"caption\":\"Nesa srl\"},\"image\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/nesa-srl\/\",\"https:\/\/www.facebook.com\/nesasrl\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Idrologico - Nesa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/idrologico\/","og_locale":"en_US","og_type":"article","og_title":"Idrologico - Nesa","og_description":"Sistemi per il controllo dei livelli, della qualit\u00e0 delle acque e sistemi di allertamento per il rischio idrogeologico, con le migliori tecnologie. Stazioni professionali realizzate ai fini della misura e del controllo del rischio idrico: piogge, esondazioni, piene, fenomeni torrentizi, qualit\u00e0 dell&#8217;acqua ecc. Le nostre soluzioni sono modulari e flessibili, di tipo tradizionale con datalogger, &hellip; Idrologico Read More &raquo;","og_url":"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/idrologico\/","og_site_name":"Nesa","article_publisher":"https:\/\/www.facebook.com\/nesasrl","article_modified_time":"2022-05-05T11:08:02+00:00","og_image":[{"width":1920,"height":900,"url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/nesa_slide-home-mountain-bg5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/idrologico\/","url":"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/idrologico\/","name":"Idrologico - Nesa","isPartOf":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#website"},"datePublished":"2021-10-14T13:38:35+00:00","dateModified":"2022-05-05T11:08:02+00:00","breadcrumb":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/idrologico\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nesasrl.sp2.netkom.it\/sistemi\/idrologico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/idrologico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nesasrl.sp2.netkom.it\/it\/"},{"@type":"ListItem","position":2,"name":"Sistemi","item":"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/"},{"@type":"ListItem","position":3,"name":"Idrologico"}]},{"@type":"WebSite","@id":"https:\/\/nesasrl.sp2.netkom.it\/#website","url":"https:\/\/nesasrl.sp2.netkom.it\/","name":"Nesa","description":"Sistemi per il monitoraggio ambientale e telecontrollo","publisher":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization","name":"Nesa srl","url":"https:\/\/nesasrl.sp2.netkom.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/","url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","contentUrl":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","width":264,"height":55,"caption":"Nesa srl"},"image":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/nesa-srl\/","https:\/\/www.facebook.com\/nesasrl"]}]}},"_links":{"self":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/pages\/1401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/comments?post=1401"}],"version-history":[{"count":72,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/pages\/1401\/revisions"}],"predecessor-version":[{"id":14531,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/pages\/1401\/revisions\/14531"}],"up":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/pages\/131"}],"wp:attachment":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/media?parent=1401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}