{"id":131,"date":"2021-09-29T15:31:58","date_gmt":"2021-09-29T13:31:58","guid":{"rendered":"http:\/\/164.90.193.213\/?page_id=131"},"modified":"2022-05-05T13:04:50","modified_gmt":"2022-05-05T11:04:50","slug":"sistemi","status":"publish","type":"page","link":"https:\/\/nesasrl.sp2.netkom.it\/it\/sistemi\/","title":{"rendered":"Sistemi"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"131\" class=\"elementor elementor-131\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ea165e1 elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"ea165e1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8910db2\" data-id=\"8910db2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47ea4f7 elementor-widget elementor-widget-heading\" data-id=\"47ea4f7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-xl\">Sistemi<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-87b2b62 elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"87b2b62\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2aff802\" data-id=\"2aff802\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb9d629 elementor-widget elementor-widget-spacer\" data-id=\"fb9d629\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.e-container.e-container--row .elementor-spacer-inner{width:var(--spacer-size)}.e-container.e-container--column .elementor-spacer-inner,.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b2e58fd\" data-id=\"b2e58fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e34d551 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"e34d551\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-660a027\" data-id=\"660a027\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ed1ff0 elementor-widget elementor-widget-text-editor\" data-id=\"0ed1ff0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Progettiamo, produciamo e installiamo <span style=\"color: #0075BE;\">sistemi completi<\/span> per la prevenzione e la sicurezza ambientale.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-65cd1f6\" data-id=\"65cd1f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f87d5a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f87d5a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-746a08e\" data-id=\"746a08e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4699121 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4699121\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-666239c\" data-id=\"666239c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa50e84 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"aa50e84\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text-center icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1\" data-name=\"Livello 1\" viewBox=\"0 0 300 300\"><defs><style>.cls-1{fill:#728895;}<\/style><\/defs><path class=\"cls-1\" d=\"M145.94,224.88a2.14,2.14,0,0,0-.5.06,1.92,1.92,0,0,0-1.17.9l-9,15.45a1.92,1.92,0,0,0,.71,2.62,1.94,1.94,0,0,0,2.62-.7l9-15.45a1.92,1.92,0,0,0-.69-2.62h0A1.9,1.9,0,0,0,145.94,224.88Z\"><\/path><path class=\"cls-1\" d=\"M174.88,224.88a2.12,2.12,0,0,0-.49.06,1.87,1.87,0,0,0-1.16.9l-9,15.45a1.92,1.92,0,0,0,.71,2.62,1.94,1.94,0,0,0,2.61-.69l9-15.46a1.93,1.93,0,0,0-.7-2.62h0A1.91,1.91,0,0,0,174.88,224.88Z\"><\/path><path class=\"cls-1\" d=\"M203.84,224.88a2.14,2.14,0,0,0-.5.06,1.87,1.87,0,0,0-1.16.9l-9,15.45a1.92,1.92,0,0,0,3.32,1.93l9-15.46a1.92,1.92,0,0,0-.7-2.62h0A1.84,1.84,0,0,0,203.84,224.88Z\"><\/path><path class=\"cls-1\" d=\"M47.92,123.94a1.91,1.91,0,1,0,0,3.82H72.36a1.91,1.91,0,0,0,0-3.82Z\"><\/path><path class=\"cls-1\" d=\"M116,55.83a1.91,1.91,0,0,0-1.92,1.91V82.18a1.92,1.92,0,0,0,3.83,0V57.74A1.91,1.91,0,0,0,116,55.83Z\"><\/path><path class=\"cls-1\" d=\"M83.8,96.32a2,2,0,0,0,2.7,0,1.91,1.91,0,0,0,0-2.7L69.22,76.33A1.91,1.91,0,0,0,66.52,79Z\"><\/path><path class=\"cls-1\" d=\"M164.19,75.78a2,2,0,0,0-1.36.56L145.55,93.62a1.91,1.91,0,0,0,0,2.7,2,2,0,0,0,2.71,0L165.54,79a1.91,1.91,0,0,0-1.35-3.26Z\"><\/path><path class=\"cls-1\" d=\"M85.17,154.83a1.94,1.94,0,0,0-1.36.56L66.54,172.67a1.88,1.88,0,0,0,0,2.7,2,2,0,0,0,2.73,0l17.25-17.27a1.9,1.9,0,0,0,0-2.7h0a1.88,1.88,0,0,0-1.34-.56Z\"><\/path><path class=\"cls-1\" d=\"M116,97.87a28,28,0,0,0-10.34,54l2.34.93-2.34.93a28,28,0,0,0,10.27,54H220.21a2.14,2.14,0,0,0,.62-.11l.22,0a36.09,36.09,0,0,0-1.4-72l-.66,0-.23-.62a54,54,0,0,0-79.9-26.67l-.74.48-.57-.69A27.86,27.86,0,0,0,116,97.87Zm103.59,106H116a24.15,24.15,0,1,1,0-48.3,1.92,1.92,0,0,0,1.91-1.91c0-.46,0-.92,0-1.37l0-.66a50,50,0,0,1,1-8.25L119,143c.16-.74.32-1.44.5-2.13.14-.51.28-1,.43-1.49.07-.25.13-.45.2-.66l.06-.21c.21-.68.44-1.34.67-2a.81.81,0,0,0,0-.15l0-.1a50.23,50.23,0,0,1,16.54-22.44l.79-.6A50.18,50.18,0,0,1,215.8,138a1.88,1.88,0,0,0,1.81,1.31h.27a32.27,32.27,0,0,1,2.2,64.47,1.86,1.86,0,0,0-.34.05ZM114.17,149.94l-1-.12a24.15,24.15,0,1,1,21.19-39.7l.68.79-.81.64a53.31,53.31,0,0,0-18.44,28.54l0,.11a3.25,3.25,0,0,1-.11.42c0,.25-.11.5-.17.75l-.11.47c-.11.5-.22,1-.32,1.52a1.67,1.67,0,0,0-.05.31l0,.17c-.14.74-.26,1.5-.37,2.26l0,.11c-.12.9-.22,1.81-.31,2.72Z\"><\/path><\/svg>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h2 class=\"elementskit-info-box-title\">\n                    Meteo                <\/h2>\n                                                    <div class=\"box-footer disable_hover_button\">\n                    <div class=\"btn-wraper\">\n                                                            <a href=\"https:\/\/nesasrl.sp2.netkom.it\/it\/categoria_prodotti\/meteo\/\" target=\"_self\" rel=\"\" class=\"elementskit-btn whitespace--normal elementor-animation-\">\n                                        Approfondisci                                    <\/a>\n                                                        <\/div>\n                <\/div>\n                    <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1e17338\" data-id=\"1e17338\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f12727c ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"f12727c\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text-center icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1\" data-name=\"Livello 1\" viewBox=\"0 0 300 300\"><defs><style>.cls-1{fill:#728895;}<\/style><\/defs><path class=\"cls-1\" d=\"M150,58.45A91.55,91.55,0,1,0,241.55,150,91.65,91.65,0,0,0,150,58.45ZM157.52,62a88.49,88.49,0,0,1,79.93,75.58l.08.53H211.48c0-3.23,0-10.38-.88-13.82-1.11-4.43-7.71-18.71-9.78-22.24C199,99,189.7,94.3,181.11,90.14l-2.47-1.2c-4-2-13.8-4.27-21.62-3.83V62Zm53.22,116.6c-1,7.76-11.94,20.55-24.45,28.51-9.1,5.79-11.63,2.47-16.22-3.56-.94-1.24-1.91-2.52-3-3.83-6-7-15.07-7.79-27.68-9-1.77-.16-3.61-.33-5.51-.53-11.38-1.16-11.76-5.83-12.46-14.33-.11-1.4-.24-2.93-.43-4.53a148.32,148.32,0,0,0,26.87,2.46,147.44,147.44,0,0,0,63-14.25C211.08,163,211.58,171.84,210.74,178.59Zm-62.91-8a144.33,144.33,0,0,1-30.55-3.27l-1.07-.23,6.06-3.94c3.11.14,11.6.56,23.66,1.41,1.42.09,2.81.14,4.18.14,9.77,0,18.26-2.38,27.19-4.89,3.52-1,7.15-2,10.86-2.86,12.13-2.8,20-12.43,22.4-15.66h24.2l-1.11.83A144.49,144.49,0,0,1,147.83,170.61ZM122,137.38l.22-.76c2.88-10,8.24-28.57,12.32-33.39,4.64-5.47,13.44-13.54,19.28-15.5V105c-3.1,1.63-11.66,6.21-15.27,8.92-3,2.23-4.45,6.11-6.31,11a93.87,93.87,0,0,1-3.74,8.86c-3.7,7.38-.08,16.94,1.52,20.47l-8.37,5.44C121,155.37,119.76,145.1,122,137.38Zm87.42.72H193.32c-.43-2.71-1.4-8.63-2.21-12.68-1.31-6.54-5.19-11.69-10.39-13.76l-1.76-.72c-5.45-2.22-13.54-5.51-21.94-6.46V87.17c7.4-.44,16.95,1.74,20.69,3.61.63.32,1.49.73,2.5,1.22,5.15,2.49,17.2,8.32,18.83,11.09,2,3.46,8.48,17.4,9.55,21.7C209.39,128,209.44,135,209.41,138.1Zm-52.39,0V106.56c8,1,15.87,4.14,21.16,6.3l1.78.72c4.54,1.81,7.95,6.39,9.12,12.24.77,3.87,1.69,9.46,2.15,12.28Zm32.54,3.21c-2.09,1.77-6.08,4.51-13.43,7.74-8.86,3.9-19.83,5.88-32.63,5.88-2.25,0-5.42-.22-7.92-.42l20.31-13.2Zm-35.75-2.48-22,14.33c-1.51-3.47-4.61-12.07-1.43-18.41a98.11,98.11,0,0,0,3.82-9c1.74-4.59,3.12-8.22,5.62-10.1,3.14-2.35,10.43-6.32,14-8.23Zm-21,17.52c2.35.21,7.42.64,10.73.64,13.08,0,24.34-2,33.46-6,9.89-4.36,14-7.92,15.61-9.64h15.37c-3,3.77-10.2,11.32-20.25,13.64-3.75.87-7.41,1.9-10.95,2.89-10,2.81-19.43,5.46-30.66,4.67-9.4-.65-16.63-1-20.85-1.27Zm21-92.39V85.55c-6.92,2-16.84,11.61-20.85,16.34-4.38,5.17-9.61,23.31-12.74,34.16l-.22.76c-2.54,8.81-.92,20.31-.26,24.17l-6.6,4.29v-1.18A142.77,142.77,0,0,1,153,64.79Zm-44.29,7.55s0,.09.06.15c.15.74,0,2.45-2.63,5.62-7.87,9.44-12.32,16.52-13.23,21-.42,2.11-2.15,3.66-4.15,5.47-2.66,2.39-5.67,5.1-6.84,10-2.65,11.07-9.32,20.56-12.92,20.56H63.06A88.6,88.6,0,0,1,109.52,71.51ZM61.67,150q0-1.51.06-3c2.71.88,7.59,3,9.1,7.17a17.93,17.93,0,0,0,8.37,10.18l.19.11c1.47.88,4.39,5.84,5.56,10.15,1.28,4.68,6.83,11.4,9.32,12.64.54.27-.17,3.31-.55,4.95a32.33,32.33,0,0,0-1.1,7.13c0,3.9.16,13.17.25,18A88.16,88.16,0,0,1,61.67,150ZM150,238.33A87.92,87.92,0,0,1,95,219c-.07-3.84-.28-15.3-.28-19.74a31,31,0,0,1,1-6.66c.82-3.5,1.46-6.27-.53-7.26S88.08,178.2,87,174s-4.22-10-6.5-11.38l-.19-.12a15.75,15.75,0,0,1-7.48-9.1c-1.94-5.35-8-7.75-11-8.61q.26-4.28.9-8.43h7.09c6.41,0,13-14.19,14.93-22.13,1-4.27,3.66-6.64,6.21-8.94,2.18-2,4.24-3.81,4.8-6.6.82-4.12,5.25-11.08,12.78-20.13,2.48-3,3.51-5.48,3-7.46a2.93,2.93,0,0,0-.19-.57A87.73,87.73,0,0,1,150,61.67h1.55l-.75.77a146,146,0,0,0-40.87,101.64c0,1.22,0,2.45,0,3.67a1.58,1.58,0,0,0,.5,1.12,1.61,1.61,0,0,0,.83.42l.11,0a1.68,1.68,0,0,0,.67.16l.09,0h.13c2.16.54,4.34,1,6.52,1.45.23,1.79.38,3.48.51,5.13.69,8.32,1.23,14.88,14.31,16.22,1.91.2,3.75.37,5.52.53,12.13,1.12,20.9,1.94,26.31,8.25,1.08,1.26,2,2.51,3,3.73,2.91,3.83,5.57,7.33,10.1,7.33,2.35,0,5.2-1,8.87-3.28,11.55-7.35,24.21-20.58,25.39-30,1-7.66.26-17.67.06-20.23a145.77,145.77,0,0,0,24.51-15.25l.68-.52.06.86c.15,2.13.23,4.25.23,6.3A88.42,88.42,0,0,1,150,238.33Z\"><\/path><\/svg>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h2 class=\"elementskit-info-box-title\">\n                    Geotecnico                <\/h2>\n                                                    <div class=\"box-footer disable_hover_button\">\n                    <div class=\"btn-wraper\">\n                                                            <a href=\"https:\/\/nesasrl.sp2.netkom.it\/it\/categoria_prodotti\/geotecnico\/\" target=\"_self\" rel=\"\" class=\"elementskit-btn whitespace--normal elementor-animation-\">\n                                        Approfondisci                                    <\/a>\n                                                        <\/div>\n                <\/div>\n                    <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c2c4d00 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c2c4d00\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-dec1e12\" data-id=\"dec1e12\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1476a5e ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"1476a5e\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text- icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1\" data-name=\"Livello 1\" viewBox=\"0 0 300 300\"><defs><style>.cls-1{fill:#728895;}<\/style><\/defs><path class=\"cls-1\" d=\"M62.11,182.35a1.5,1.5,0,1,0,0,3H237.85a1.5,1.5,0,0,0,0-3h-39.2v-22.7l.7-.05a36.71,36.71,0,1,0-4.41,0l.7.05v22.7h-85V145.89l.71,0a42.9,42.9,0,1,0-4.43,0l.71,0v36.46Zm136.54-25.7v-13.4l11.9-11.92a1.51,1.51,0,1,0-2.13-2.13L198.65,139V122.81a1.51,1.51,0,1,0-3,0V139l-9.77-9.79a1.51,1.51,0,1,0-2.13,2.13l11.9,11.92v13.4l-.8-.06a33.69,33.69,0,1,1,4.61,0ZM107.6,142.89l-.79,0a39.88,39.88,0,1,1,4.59,0l-.79,0V126.75l14.07-14.09a1.51,1.51,0,1,0-2.13-2.13l-11.94,12V102.82a1.51,1.51,0,0,0-3,0V122.5l-11.94-12a1.51,1.51,0,0,0-2.13,2.13l14.07,14.09Z\"><\/path><path class=\"cls-1\" d=\"M212.79,203.78l.63,1a14.07,14.07,0,0,0,11.92,6.45,13.87,13.87,0,0,0,14.06-13.64,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.5,1.5,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.5,1.5,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,0,0-3,0,11.06,11.06,0,0,1-22.1,0,1.5,1.5,0,0,0-3,0A13.86,13.86,0,0,0,74.7,211.21a14.07,14.07,0,0,0,11.92-6.45l.64-1,.63,1a14.24,14.24,0,0,0,23.84,0l.63-1,.63,1a14.25,14.25,0,0,0,23.85,0l.63-1,.63,1a14.24,14.24,0,0,0,23.84,0l.63-1,.64,1a14.24,14.24,0,0,0,23.84,0l.63-1,.63,1a14.25,14.25,0,0,0,23.85,0Z\"><\/path><path class=\"cls-1\" d=\"M212.79,232l.63,1a14.09,14.09,0,0,0,11.92,6.45,13.87,13.87,0,0,0,14.06-13.64,1.51,1.51,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.5,1.5,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.5,1.5,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.51,1.51,0,1,0-3,0,11.06,11.06,0,0,1-22.1,0,1.5,1.5,0,1,0-3,0A13.86,13.86,0,0,0,74.7,239.43,14.09,14.09,0,0,0,86.62,233l.64-1,.63,1a14.24,14.24,0,0,0,23.84,0l.63-1,.63,1a14.25,14.25,0,0,0,23.85,0l.63-1,.63,1a14.24,14.24,0,0,0,23.84,0l.63-1,.64,1a14.24,14.24,0,0,0,23.84,0l.63-1,.63,1a14.25,14.25,0,0,0,23.85,0Z\"><\/path><\/svg>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h2 class=\"elementskit-info-box-title\">\n                    Idrologico                <\/h2>\n                                                    <div class=\"box-footer disable_hover_button\">\n                    <div class=\"btn-wraper\">\n                                                            <a href=\"https:\/\/nesasrl.sp2.netkom.it\/it\/categoria_prodotti\/idrologico\/\" target=\"_self\" rel=\"\" class=\"elementskit-btn whitespace--normal elementor-animation-\">\n                                        Approfondisci                                    <\/a>\n                                                        <\/div>\n                <\/div>\n                    <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-dd7b44b\" data-id=\"dd7b44b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba54503 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"ba54503\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text-center icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1\" data-name=\"Livello 1\" viewBox=\"0 0 300 300\"><defs><style>.cls-1{fill:#728895;}<\/style><\/defs><path class=\"cls-1\" d=\"M198,130.6c-1.59-2.33-3.37-4.94-5.26-7.91-12.33-19.32-3.4-26.85,3.77-32.91l.77-.64c9.93-8.43,26.43-16.36,33.07-19.38a1.25,1.25,0,0,0-.52-2.38,1.19,1.19,0,0,0-.52.11c-6.73,3.06-23.48,11.11-33.65,19.74l-.76.64c-7.5,6.33-17.77,15-4.27,36.17,1.93,3,3.73,5.65,5.31,8,5,7.34,8.05,11.78,7.15,16.68s-5.56,10.7-17.21,21.58c-7.78,7.25-21.17,16.26-21.74,16.64a1.26,1.26,0,0,0-.53.8,1.25,1.25,0,0,0,.19.94,1.27,1.27,0,0,0,1.73.34c.14-.09,13.89-9.28,22.05-16.89C210.51,150.75,209,146.61,198,130.6Z\"><\/path><path class=\"cls-1\" d=\"M239.69,77.87a1.31,1.31,0,0,0,.43-.08l.45-.19,3-1.23a1.13,1.13,0,0,0-.86-2.08l-3,1.23-.46.18a1.13,1.13,0,0,0,.42,2.17Z\"><\/path><path class=\"cls-1\" d=\"M224.63,149h.15a1.12,1.12,0,0,0,1.12-1,25.3,25.3,0,0,0,.24-3.44,23.63,23.63,0,0,0-.39-4.27,1.12,1.12,0,1,0-2.21.41,21.71,21.71,0,0,1,.35,3.85,22.17,22.17,0,0,1-.22,3.13A1.11,1.11,0,0,0,224.63,149Z\"><\/path><path class=\"cls-1\" d=\"M230.54,80.64a1.12,1.12,0,0,0-1.5-.53c-2.48,1.18-4.65,2.32-6.62,3.5a1.13,1.13,0,0,0-.38,1.55,1.13,1.13,0,0,0,1.54.38c1.91-1.14,4-2.25,6.43-3.4A1.12,1.12,0,0,0,230.54,80.64Z\"><\/path><path class=\"cls-1\" d=\"M200.92,187.61a1.12,1.12,0,0,0-1.59.1c-1.53,1.74-3.15,3.53-4.93,5.46a1.12,1.12,0,1,0,1.65,1.52c1.8-1.94,3.42-3.74,5-5.5A1.11,1.11,0,0,0,200.92,187.61Z\"><\/path><path class=\"cls-1\" d=\"M217.25,165.78a1.13,1.13,0,0,0,1.54-.38c1.43-2.38,2.61-4.53,3.59-6.57a1.12,1.12,0,0,0-2-1c-.95,2-2.09,4.06-3.49,6.38A1.12,1.12,0,0,0,217.25,165.78Z\"><\/path><path class=\"cls-1\" d=\"M206.6,180.85a1.11,1.11,0,0,0,.69.24,1.13,1.13,0,0,0,.89-.43c1.61-2,3.12-4,4.48-5.94a1.12,1.12,0,1,0-1.83-1.3c-1.34,1.87-2.82,3.84-4.42,5.85A1.13,1.13,0,0,0,206.6,180.85Z\"><\/path><path class=\"cls-1\" d=\"M210.32,116.09a1.15,1.15,0,0,0,.5-.12,1.13,1.13,0,0,0,.5-1.51,22.87,22.87,0,0,1-2.25-6.64,1.13,1.13,0,0,0-2.23.35,25,25,0,0,0,2.47,7.29A1.12,1.12,0,0,0,210.32,116.09Z\"><\/path><path class=\"cls-1\" d=\"M219.58,130.87a1.13,1.13,0,0,0,1,.55,1.1,1.1,0,0,0,.57-.16,1.12,1.12,0,0,0,.39-1.54,69.25,69.25,0,0,0-4.21-6.21,1.13,1.13,0,0,0-1.8,1.35A65,65,0,0,1,219.58,130.87Z\"><\/path><path class=\"cls-1\" d=\"M215.12,92.14a1.12,1.12,0,0,0-1.64-1.54,28.27,28.27,0,0,0-1.85,2.19,33.24,33.24,0,0,0-2.64,4,1.12,1.12,0,0,0,.44,1.53,1.17,1.17,0,0,0,.54.14,1.13,1.13,0,0,0,1-.58,31.31,31.31,0,0,1,2.47-3.73A24,24,0,0,1,215.12,92.14Z\"><\/path><path class=\"cls-1\" d=\"M186.79,201.28c-1.33,1.44-2.09,2.31-2.54,2.91a1.12,1.12,0,1,0,1.8,1.35c.4-.53,1.14-1.37,2.39-2.72a1.13,1.13,0,0,0-1.65-1.54Z\"><\/path><path class=\"cls-1\" d=\"M257.62,81.57a1.25,1.25,0,0,0-1.17-.79,1.19,1.19,0,0,0-.45.08c-2.31.91-4.61,1.72-6.83,2.5-9.47,3.36-18.37,6.51-21.78,14.93-3.83,9.46,3.08,17.78,11.11,25.36,9.57,9,9.61,25.35.12,48.45-7.69,18.71-22.74,36-31.73,46.27-2.46,2.82-4.41,5-5.6,6.63a1.29,1.29,0,0,0-.24.93,1.24,1.24,0,0,0,.49.82,1.27,1.27,0,0,0,1.75-.24c1.13-1.5,3-3.7,5.46-6.47,9.12-10.45,24.34-27.9,32.18-47,9.93-24.16,9.69-41.39-.72-51.22-10.23-9.66-13.18-16-10.5-22.6,3-7.38,10.6-10.08,20.25-13.49,2.25-.8,4.58-1.62,7-2.55A1.26,1.26,0,0,0,257.62,81.57Z\"><\/path><path class=\"cls-1\" d=\"M148.49,214.82a1.21,1.21,0,0,1-.92-.42,1.22,1.22,0,0,1,.1-1.72c6.64-5.89,15.55-18.29,20.21-43.8a1.23,1.23,0,1,1,2.42.43c-4.79,26.2-14.07,39-21,45.19A1.06,1.06,0,0,1,148.49,214.82Z\"><\/path><path class=\"cls-1\" d=\"M88.25,214.82a1.27,1.27,0,0,1-.82-.29c-6.94-6.17-16.22-19-21-45.2a1.23,1.23,0,0,1,2.43-.42c4.66,25.5,13.57,37.9,20.21,43.79a1.23,1.23,0,0,1,.1,1.73A1.14,1.14,0,0,1,88.25,214.82Z\"><\/path><path class=\"cls-1\" d=\"M170,132.17a1.23,1.23,0,0,1-1.22-1,47.34,47.34,0,0,0-14-23.39,53.82,53.82,0,0,0-72.8,0,47.54,47.54,0,0,0-14,23.41,1.19,1.19,0,0,1-.3.55,1.25,1.25,0,0,1-1.74.05,1.2,1.2,0,0,1-.28-1.37A49.62,49.62,0,0,1,80.31,106a56.26,56.26,0,0,1,76.12,0,49.29,49.29,0,0,1,14.72,24.68,1,1,0,0,1,0,.3A1.24,1.24,0,0,1,170,132.17Z\"><\/path><path class=\"cls-1\" d=\"M118.37,235.09a23.36,23.36,0,1,1,23.36-23.36A23.39,23.39,0,0,1,118.37,235.09Zm0-44.25a20.89,20.89,0,1,0,20.89,20.89A20.92,20.92,0,0,0,118.37,190.84Z\"><\/path><path class=\"cls-1\" d=\"M118.37,243.12a31.41,31.41,0,1,1,31.42-31.41A31.46,31.46,0,0,1,118.37,243.12Zm0-60.34a29,29,0,1,0,28.95,28.95A29,29,0,0,0,118.37,182.78Z\"><\/path><path class=\"cls-1\" d=\"M168.76,250.84a3.77,3.77,0,0,1-1.85-.5l-13.83-8a3.7,3.7,0,0,1-1.34-5.07l16.12-27.9a3.69,3.69,0,0,1,5.06-1.34l13.83,8a3.72,3.72,0,0,1,1.35,5.07h0L172,249a3.71,3.71,0,0,1-2.25,1.72A4.11,4.11,0,0,1,168.76,250.84ZM171.08,210a1.88,1.88,0,0,0-.33.05,1.29,1.29,0,0,0-.77.58l-16.12,27.9a1.26,1.26,0,0,0,.45,1.72l13.82,8a1.18,1.18,0,0,0,1,.12,1.31,1.31,0,0,0,.77-.57L186,219.87h0a1.29,1.29,0,0,0-.45-1.73l-13.83-8A1.09,1.09,0,0,0,171.08,210Zm16,10.48Z\"><\/path><path class=\"cls-1\" d=\"M166.21,215.92a1.21,1.21,0,0,1-.62-.17l-12.21-7a1.23,1.23,0,1,1,1.23-2.12l12.2,7a1.21,1.21,0,0,1,.45,1.67A1.17,1.17,0,0,1,166.21,215.92Z\"><\/path><path class=\"cls-1\" d=\"M155.53,234.41a1.21,1.21,0,0,1-.62-.17l-11-6.36a1.22,1.22,0,0,1-.45-1.68,1.2,1.2,0,0,1,1.67-.44l11,6.36a1.21,1.21,0,0,1,.45,1.67A1.15,1.15,0,0,1,155.53,234.41Z\"><\/path><path class=\"cls-1\" d=\"M163.52,248.19a1.25,1.25,0,0,1-.63-.17,1.22,1.22,0,0,1-.45-1.68l18.62-32.19a1.26,1.26,0,0,1,1.67-.45,1.21,1.21,0,0,1,.45,1.67l-18.62,32.2A1.16,1.16,0,0,1,163.52,248.19Z\"><\/path><path class=\"cls-1\" d=\"M68,250.84a4.12,4.12,0,0,1-1-.13A3.71,3.71,0,0,1,64.77,249l-16.12-27.9h0a3.7,3.7,0,0,1-.38-2.82A3.74,3.74,0,0,1,50,216l13.83-8a3.7,3.7,0,0,1,2.82-.38,3.74,3.74,0,0,1,2.25,1.72L85,237.28a3.72,3.72,0,0,1-1.35,5.07l-13.83,8A3.74,3.74,0,0,1,68,250.84Zm-17.22-31,16.12,27.9a1.2,1.2,0,0,0,.77.57,1.31,1.31,0,0,0,1-.12l13.83-8a1.26,1.26,0,0,0,.44-1.72l-16.12-27.9A1.21,1.21,0,0,0,66,210a1.27,1.27,0,0,0-.95.13l-13.82,8a1.27,1.27,0,0,0-.45,1.73Z\"><\/path><path class=\"cls-1\" d=\"M70.53,215.92a1.26,1.26,0,0,1-1.07-.62,1.19,1.19,0,0,1,.45-1.67l12.18-7.07a1.23,1.23,0,0,1,1.22,2.13l-12.18,7.06A1.07,1.07,0,0,1,70.53,215.92Z\"><\/path><path class=\"cls-1\" d=\"M81.21,234.41a1.23,1.23,0,0,1-1.07-.62,1.19,1.19,0,0,1,.45-1.67l11-6.36a1.22,1.22,0,1,1,1.22,2.12l-11,6.36A1,1,0,0,1,81.21,234.41Z\"><\/path><path class=\"cls-1\" d=\"M73.23,248.19a1.27,1.27,0,0,1-1.08-.62l-18.61-32.2a1.22,1.22,0,0,1,2.12-1.22l18.62,32.19a1.21,1.21,0,0,1-.45,1.68A1.09,1.09,0,0,1,73.23,248.19Z\"><\/path><path class=\"cls-1\" d=\"M151.94,176.32a42,42,0,0,1-33.57-16.42,41.85,41.85,0,0,1-33.46,16.42c-7.86,0-13.85-2-17.85-6-5.94-5.91-5.94-14.2-5.91-19.69v-1.72c-.13-6.47.42-14.55,5.64-19.77,3-3,7.24-4.61,12.33-4.49h78.63c5-.1,9.16,1.4,12.28,4.49h0c5.21,5.22,5.76,13.3,5.64,19.77v1.72c0,5.49,0,13.78-5.92,19.69C165.69,174.27,159.7,176.32,151.94,176.32Zm-33.57-19.69a1.27,1.27,0,0,1,1,.5,39.54,39.54,0,0,0,32.47,16.72c7.18,0,12.57-1.8,16.12-5.32,5.21-5.19,5.21-12.85,5.21-17.94v-1.77c.1-6-.35-13.43-4.91-18h0c-2.6-2.6-6.14-3.87-10.51-3.77H79.07c-4.45-.13-8,1.17-10.56,3.77-4.57,4.56-5,12-4.92,18v1.77c0,5.07,0,12.75,5.22,17.94,3.52,3.52,8.91,5.32,16,5.32a39.63,39.63,0,0,0,32.57-16.72A1.1,1.1,0,0,1,118.37,156.63ZM84.56,169.51c-5.67,0-10.06-1.4-12.71-4-3.94-3.91-3.91-10.25-3.91-14.87v-1.85c-.08-4.71.2-11.38,3.64-14.82,1.67-1.67,4-2.5,7.06-2.5H157.8c3.29,0,5.67.78,7.39,2.5,3.44,3.44,3.72,10.11,3.64,14.82h0v1.85c0,4.62,0,10.93-3.92,14.85-2.69,2.67-7,4-12.95,4-22.16,0-31.22-18.24-31.59-19a2.25,2.25,0,0,0-3.92,0c-.08.17-9.18,19-31.52,19A1.67,1.67,0,0,1,84.56,169.51ZM78.62,133.9c-2.4,0-4.12.57-5.32,1.77-3.09,3.09-3,10.58-2.92,13.05v1.87c0,4.19,0,9.91,3.22,13.13,2.22,2.22,6.24,3.37,11.28,3.32,20.59,0,29.22-17.45,29.32-17.62a4.68,4.68,0,0,1,4.17-2.65,4.61,4.61,0,0,1,4.17,2.65c.35.72,8.76,17.57,29.3,17.62,5.31,0,9.08-1.13,11.28-3.32,3.22-3.2,3.22-8.94,3.22-13.1v-1.9h0c.07-4.27-.15-10.28-2.92-13.05-1.25-1.25-3-1.82-5.64-1.77H78.62Z\"><\/path><\/svg>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h2 class=\"elementskit-info-box-title\">\n                    Aria, strade e gas                <\/h2>\n                                                    <div class=\"box-footer disable_hover_button\">\n                    <div class=\"btn-wraper\">\n                                                            <a href=\"https:\/\/nesasrl.sp2.netkom.it\/it\/categoria_prodotti\/aria-strade-e-gas\/\" target=\"_self\" rel=\"\" class=\"elementskit-btn whitespace--normal elementor-animation-\">\n                                        Approfondisci                                    <\/a>\n                                                        <\/div>\n                <\/div>\n                    <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9753884 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9753884\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3220877\" data-id=\"3220877\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9a2e9a ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"f9a2e9a\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text-center icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1\" data-name=\"Livello 1\" viewBox=\"0 0 300 300\"><defs><style>.cls-1{fill:#728895;}<\/style><\/defs><path class=\"cls-1\" d=\"M159.51,198.86h15v30.38c0,3.87,3.79,7,8.44,7h.25A1.65,1.65,0,0,0,183,233c-2.8,0-5.16-1.69-5.16-3.7v-30.4h19.4a1.67,1.67,0,0,0,1.66-1.66V180.34H220.6a1.66,1.66,0,0,0,0-3.31H198.86V162h30.38c2,0,3.71,2.31,3.71,5.16a1.65,1.65,0,0,0,1.65,1.65h0a1.67,1.67,0,0,0,1.18-.48,1.71,1.71,0,0,0,.48-1.19c0-4.67-3.15-8.45-7-8.45h-30.4V143.8H220.6a1.66,1.66,0,0,0,0-3.31H198.86v-15h30.4c3.85,0,7-3.8,7-8.48a1.66,1.66,0,1,0-3.31,0c0,2.84-1.66,5.16-3.7,5.16h-30.4V102.82a1.66,1.66,0,0,0-1.66-1.65H180.34V79.39a1.66,1.66,0,0,0-3.31,0v21.78H162V70.74c0-2,2.32-3.7,5.17-3.7a1.66,1.66,0,0,0,0-3.31c-4.66,0-8.44,3.15-8.44,7v30.43h-15V79.39a1.66,1.66,0,0,0-3.31,0v21.78h-15V70.74c0-3.86-3.78-7-8.43-7A1.66,1.66,0,0,0,117,67c2.85,0,5.16,1.66,5.16,3.7v30.43H102.82a1.65,1.65,0,0,0-1.65,1.65v16.83H79.39a1.65,1.65,0,0,0,0,3.3h21.78v15H70.74c-2,0-3.7-2.32-3.7-5.17a1.66,1.66,0,0,0-3.31,0c0,4.65,3.15,8.44,7,8.44h30.43v15H79.39a1.65,1.65,0,1,0,0,3.3h21.78v15H70.75c-3.87,0-7,3.79-7,8.44a1.65,1.65,0,0,0,3.3,0c0-2.83,1.66-5.15,3.7-5.15h30.43V197.2a1.66,1.66,0,0,0,1.65,1.66h16.83v21.73a1.66,1.66,0,0,0,.49,1.17A1.65,1.65,0,0,0,123,220.6V198.86h15v30.38c0,2-2.32,3.71-5.17,3.71a1.65,1.65,0,1,0,0,3.3c4.68,0,8.48-3.13,8.48-7v-30.4h15v21.73a1.65,1.65,0,1,0,3.3,0Zm36-3.31H104.44V104.44h91.11Z\"><\/path><path class=\"cls-1\" d=\"M150.21,140.74a29.73,29.73,0,0,0-7.21.9,27,27,0,0,0-12.24,7,2.42,2.42,0,0,0,1.09,4.08,2.4,2.4,0,0,0,2.34-.69,22.53,22.53,0,0,1,31.57,0,2.41,2.41,0,0,0,4.08-1.09,2.41,2.41,0,0,0-.69-2.34,26.61,26.61,0,0,0-18.5-7.89Z\"><\/path><path class=\"cls-1\" d=\"M150,133.34a34.64,34.64,0,0,1,10.27,1.56,34.27,34.27,0,0,1,14.14,8.49,2.61,2.61,0,0,0,1.76.83l.64-.09a2.43,2.43,0,0,0,1-4.14c-9.6-9.2-21.09-12.88-34.17-10.93A38.22,38.22,0,0,0,122.19,140a2.41,2.41,0,0,0-.08,3.51,2.52,2.52,0,0,0,1.75.69,2.44,2.44,0,0,0,1.72-.77A34.54,34.54,0,0,1,150,133.34Z\"><\/path><path class=\"cls-1\" d=\"M149.94,152.72a15.21,15.21,0,0,0-10.71,4.46,2.41,2.41,0,0,0,1.79,4.13,2.53,2.53,0,0,0,1.67-.75,10.47,10.47,0,0,1,14.65,0,2.4,2.4,0,1,0,3.39-3.41A15.12,15.12,0,0,0,150,152.72h-.1Z\"><\/path><path class=\"cls-1\" d=\"M150,164.53a3.47,3.47,0,0,0-3.45,3.5,3.46,3.46,0,1,0,3.46-3.5Z\"><\/path><\/svg>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h2 class=\"elementskit-info-box-title\">\n                    IoT 4.0                <\/h2>\n                                                    <div class=\"box-footer disable_hover_button\">\n                    <div class=\"btn-wraper\">\n                                                            <a href=\"https:\/\/nesasrl.sp2.netkom.it\/it\/categoria_prodotti\/iot-4-0\/\" target=\"_self\" rel=\"\" class=\"elementskit-btn whitespace--normal elementor-animation-\">\n                                        Approfondisci                                    <\/a>\n                                                        <\/div>\n                <\/div>\n                    <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0a9d253\" data-id=\"0a9d253\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0120e9f elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"0120e9f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ec2686\" data-id=\"7ec2686\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f8a5cc2 bordo-nesa elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f8a5cc2\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ad4dcc2\" data-id=\"ad4dcc2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd94833 elementor-widget elementor-widget-shortcode\" data-id=\"bd94833\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f6-o1\" lang=\"it-IT\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/131#wpcf7-f6-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f6-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<div><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome e cognome*\" \/><\/span><\/div>\n<div><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email*\" \/><\/span><\/div>\n<div class=\"elementor-row\">\n<div class=\"nesa-row-sx form-positive\"><span class=\"wpcf7-form-control-wrap\" data-name=\"company\"><input type=\"text\" name=\"company\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Azienda*\" \/><\/span><\/div>\n<div class=\"nesa-row-dx form-positive\"><span class=\"wpcf7-form-control-wrap\" data-name=\"address\"><input type=\"text\" name=\"address\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Indirizzo\" \/><\/span><\/div>\n<\/div>\n<div class=\"elementor-row\">\n<div class=\"nesa-row-sx\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-city\"><input type=\"text\" name=\"your-city\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Citt\u00e0 \/ Provincia*\" \/><\/span><\/div>\n<div class=\"nesa-row-dx\"><span class=\"wpcf7-form-control-wrap\" data-name=\"phone\"><input type=\"tel\" name=\"phone\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Numero di telefono*\" \/><\/span><\/div>\n<\/div>\n<div><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Messaggio\"><\/textarea><\/span><\/div>\n<div class=\"privacy\">*campi obbligatori<\/div>\n<div class=\"privacy\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Ho letto la <a href=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/10\/INFORMATIVA-PRIVACY-NESA-IT.pdf\" target=\"_blank\">Privacy Policy<\/a> e acconsento al trattamento dei dati personali ai sensi del Regolamento UE n. 679\/2016.<\/span><\/label><\/span><\/span><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"newsletter\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"newsletter[]\" value=\"Iscrivimi alla newsletter.\" \/><span class=\"wpcf7-list-item-label\">Iscrivimi alla newsletter.<\/span><\/span><\/span><\/span>\n<\/div>\n<div style=\"text-align: right;\"><input type=\"submit\" value=\"INVIA\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/><\/div>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f454e6c\" data-id=\"f454e6c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9544a1d elementor-widget elementor-widget-text-editor\" data-id=\"9544a1d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>CONTATTACI SENZA IMPEGNO<\/p><p>Siamo a tua disposizione per qualsiasi informazione, o chiamaci al<br \/><strong>+39 0423 985209<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sistemi Progettiamo, produciamo e installiamo sistemi completi per la prevenzione e la sicurezza ambientale. Meteo Approfondisci Geotecnico Approfondisci Idrologico Approfondisci Aria, strade e gas Approfondisci IoT 4.0 Approfondisci CONTATTACI SENZA IMPEGNO Siamo a tua disposizione per qualsiasi informazione, o chiamaci al+39 0423 985209<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":69,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"class_list":["post-131","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sistemi - Nesa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sistemi - Nesa\" \/>\n<meta property=\"og:description\" content=\"Sistemi Progettiamo, produciamo e installiamo sistemi completi per la prevenzione e la sicurezza ambientale. Meteo Approfondisci Geotecnico Approfondisci Idrologico Approfondisci Aria, strade e gas Approfondisci IoT 4.0 Approfondisci CONTATTACI SENZA IMPEGNO Siamo a tua disposizione per qualsiasi informazione, o chiamaci al+39 0423 985209\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/\" \/>\n<meta property=\"og:site_name\" content=\"Nesa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nesasrl\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-05T11:04:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/nesa_slide-home-mountain-bg5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/\",\"name\":\"Sistemi - Nesa\",\"isPartOf\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\"},\"datePublished\":\"2021-09-29T13:31:58+00:00\",\"dateModified\":\"2022-05-05T11:04:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sistemi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"name\":\"Nesa\",\"description\":\"Sistemi per il monitoraggio ambientale e telecontrollo\",\"publisher\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\",\"name\":\"Nesa srl\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"contentUrl\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"width\":264,\"height\":55,\"caption\":\"Nesa srl\"},\"image\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/nesa-srl\/\",\"https:\/\/www.facebook.com\/nesasrl\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sistemi - Nesa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/","og_locale":"en_US","og_type":"article","og_title":"Sistemi - Nesa","og_description":"Sistemi Progettiamo, produciamo e installiamo sistemi completi per la prevenzione e la sicurezza ambientale. Meteo Approfondisci Geotecnico Approfondisci Idrologico Approfondisci Aria, strade e gas Approfondisci IoT 4.0 Approfondisci CONTATTACI SENZA IMPEGNO Siamo a tua disposizione per qualsiasi informazione, o chiamaci al+39 0423 985209","og_url":"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/","og_site_name":"Nesa","article_publisher":"https:\/\/www.facebook.com\/nesasrl","article_modified_time":"2022-05-05T11:04:50+00:00","og_image":[{"width":1920,"height":900,"url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/nesa_slide-home-mountain-bg5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/","url":"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/","name":"Sistemi - Nesa","isPartOf":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#website"},"datePublished":"2021-09-29T13:31:58+00:00","dateModified":"2022-05-05T11:04:50+00:00","breadcrumb":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nesasrl.sp2.netkom.it\/sistemi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nesasrl.sp2.netkom.it\/sistemi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nesasrl.sp2.netkom.it\/it\/"},{"@type":"ListItem","position":2,"name":"Sistemi"}]},{"@type":"WebSite","@id":"https:\/\/nesasrl.sp2.netkom.it\/#website","url":"https:\/\/nesasrl.sp2.netkom.it\/","name":"Nesa","description":"Sistemi per il monitoraggio ambientale e telecontrollo","publisher":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization","name":"Nesa srl","url":"https:\/\/nesasrl.sp2.netkom.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/","url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","contentUrl":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","width":264,"height":55,"caption":"Nesa srl"},"image":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/nesa-srl\/","https:\/\/www.facebook.com\/nesasrl"]}]}},"_links":{"self":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/pages\/131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/comments?post=131"}],"version-history":[{"count":107,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/pages\/131\/revisions"}],"predecessor-version":[{"id":14525,"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/pages\/131\/revisions\/14525"}],"wp:attachment":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/it\/wp-json\/wp\/v2\/media?parent=131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}