{"id":3554,"date":"2012-09-26T13:18:00","date_gmt":"2012-09-26T11:18:00","guid":{"rendered":"http:\/\/164.90.193.213\/?p=3554"},"modified":"2023-03-01T09:30:02","modified_gmt":"2023-03-01T08:30:02","slug":"eolica-mediterranean-expo-2012","status":"publish","type":"post","link":"https:\/\/nesasrl.sp2.netkom.it\/it\/eolica-mediterranean-expo-2012\/","title":{"rendered":"EOLICA MEDITERRANEAN EXPO 2012"},"content":{"rendered":"\n<p>Nuovo appuntamento e ottimo riscontro dall&#8217;edizione 2012 per il monitoraggio eolico a norma IEC61400-12; quest&#8217;anno Nesa ha presentato oltre che i propri prodotti anche l&#8217;innovativo sistema di monitoraggio a tecnologia LIDAR prodotto dall&#8217;azienda moscovita IANS, sviluppato per l&#8217;analisi del vento fino a 300mt e a breve disponibile anche per un range esteso fino a 2000mt.<\/p>\n\n\n\n<p>Nesa e IANS hanno stretto un accordo di collaborazione per i reciproci mercati, stabilendo cos\u00ec un futuro di solida e reciproca attivit\u00e0. Nesa ha infine presentato le soluzioni di monitoraggio eolico con sensori Modbus che mediante un&#8217;interfaccia web permette di svincolare completamente l&#8217;utente dall&#8217;utilizzo di un datalogger specifico e rende possibile l&#8217;acquisizione dei dati direttamente su PC tramite interfaccia RS485\/Modbus &#8211; USB.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"205\" height=\"110\" src=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/10\/eolica_2011_prew.jpg\" alt=\"\" class=\"wp-image-3555\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Nuovo appuntamento e ottimo riscontro dall&#8217;edizione 2012 per il monitoraggio eolico a norma IEC61400-12; quest&#8217;anno Nesa ha presentato oltre che i propri prodotti anche l&#8217;innovativo sistema di monitoraggio a tecnologia LIDAR prodotto dall&#8217;azienda moscovita IANS, sviluppato per l&#8217;analisi del vento fino a 300mt e a breve disponibile anche per un range esteso fino a 2000mt. &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/nesasrl.sp2.netkom.it\/it\/eolica-mediterranean-expo-2012\/\"> <span class=\"screen-reader-text\">EOLICA MEDITERRANEAN EXPO 2012<\/span> Read More &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":3557,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-3554","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-varie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EOLICA MEDITERRANEAN EXPO 2012 - Nesa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nesasrl.sp2.netkom.it\/eolica-mediterranean-expo-2012\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EOLICA MEDITERRANEAN EXPO 2012 - Nesa\" \/>\n<meta property=\"og:description\" content=\"Nuovo appuntamento e ottimo riscontro dall&#8217;edizione 2012 per il monitoraggio eolico a norma IEC61400-12; quest&#8217;anno Nesa ha presentato oltre che i propri prodotti anche l&#8217;innovativo sistema di monitoraggio a tecnologia LIDAR prodotto dall&#8217;azienda moscovita IANS, sviluppato per l&#8217;analisi del vento fino a 300mt e a breve disponibile anche per un range esteso fino a 2000mt. &hellip; EOLICA MEDITERRANEAN EXPO 2012 Read More &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nesasrl.sp2.netkom.it\/eolica-mediterranean-expo-2012\/\" \/>\n<meta property=\"og:site_name\" content=\"Nesa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nesasrl\" \/>\n<meta property=\"article:published_time\" content=\"2012-09-26T11:18:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-01T08:30:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/10\/fotoeolica2012_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t<meta property=\"og:image:height\" content=\"270\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"moris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@moris\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"moris\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/eolica-mediterranean-expo-2012\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/eolica-mediterranean-expo-2012\/\"},\"author\":{\"name\":\"moris\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/person\/f04f829b25d9803bd3039afd4b37395a\"},\"headline\":\"EOLICA MEDITERRANEAN EXPO 2012\",\"datePublished\":\"2012-09-26T11:18:00+00:00\",\"dateModified\":\"2023-03-01T08:30:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/eolica-mediterranean-expo-2012\/\"},\"wordCount\":121,\"publisher\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\"},\"articleSection\":[\"Varie\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/eolica-mediterranean-expo-2012\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/eolica-mediterranean-expo-2012\/\",\"name\":\"EOLICA MEDITERRANEAN EXPO 2012 - Nesa\",\"isPartOf\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\"},\"datePublished\":\"2012-09-26T11:18:00+00:00\",\"dateModified\":\"2023-03-01T08:30:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/eolica-mediterranean-expo-2012\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nesasrl.sp2.netkom.it\/eolica-mediterranean-expo-2012\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/eolica-mediterranean-expo-2012\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nesasrl.sp2.netkom.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EOLICA MEDITERRANEAN EXPO 2012\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#website\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"name\":\"Nesa\",\"description\":\"Sistemi per il monitoraggio ambientale e telecontrollo\",\"publisher\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#organization\",\"name\":\"Nesa srl\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"contentUrl\":\"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg\",\"width\":264,\"height\":55,\"caption\":\"Nesa srl\"},\"image\":{\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/nesa-srl\/\",\"https:\/\/www.facebook.com\/nesasrl\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/person\/f04f829b25d9803bd3039afd4b37395a\",\"name\":\"moris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f8a6da1a0980ff05aa322b98cbd1907117e072e21dd674cbce479e811160e614?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f8a6da1a0980ff05aa322b98cbd1907117e072e21dd674cbce479e811160e614?s=96&d=mm&r=g\",\"caption\":\"moris\"},\"sameAs\":[\"https:\/\/nesasrl.sp2.netkom.it\/\",\"https:\/\/twitter.com\/moris\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EOLICA MEDITERRANEAN EXPO 2012 - Nesa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nesasrl.sp2.netkom.it\/eolica-mediterranean-expo-2012\/","og_locale":"en_US","og_type":"article","og_title":"EOLICA MEDITERRANEAN EXPO 2012 - Nesa","og_description":"Nuovo appuntamento e ottimo riscontro dall&#8217;edizione 2012 per il monitoraggio eolico a norma IEC61400-12; quest&#8217;anno Nesa ha presentato oltre che i propri prodotti anche l&#8217;innovativo sistema di monitoraggio a tecnologia LIDAR prodotto dall&#8217;azienda moscovita IANS, sviluppato per l&#8217;analisi del vento fino a 300mt e a breve disponibile anche per un range esteso fino a 2000mt. &hellip; EOLICA MEDITERRANEAN EXPO 2012 Read More &raquo;","og_url":"https:\/\/nesasrl.sp2.netkom.it\/eolica-mediterranean-expo-2012\/","og_site_name":"Nesa","article_publisher":"https:\/\/www.facebook.com\/nesasrl","article_published_time":"2012-09-26T11:18:00+00:00","article_modified_time":"2023-03-01T08:30:02+00:00","og_image":[{"width":360,"height":270,"url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/10\/fotoeolica2012_01.jpg","type":"image\/jpeg"}],"author":"moris","twitter_card":"summary_large_image","twitter_creator":"@moris","twitter_misc":{"Written by":"moris","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nesasrl.sp2.netkom.it\/eolica-mediterranean-expo-2012\/#article","isPartOf":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/eolica-mediterranean-expo-2012\/"},"author":{"name":"moris","@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/person\/f04f829b25d9803bd3039afd4b37395a"},"headline":"EOLICA MEDITERRANEAN EXPO 2012","datePublished":"2012-09-26T11:18:00+00:00","dateModified":"2023-03-01T08:30:02+00:00","mainEntityOfPage":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/eolica-mediterranean-expo-2012\/"},"wordCount":121,"publisher":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization"},"articleSection":["Varie"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/nesasrl.sp2.netkom.it\/eolica-mediterranean-expo-2012\/","url":"https:\/\/nesasrl.sp2.netkom.it\/eolica-mediterranean-expo-2012\/","name":"EOLICA MEDITERRANEAN EXPO 2012 - Nesa","isPartOf":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#website"},"datePublished":"2012-09-26T11:18:00+00:00","dateModified":"2023-03-01T08:30:02+00:00","breadcrumb":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/eolica-mediterranean-expo-2012\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nesasrl.sp2.netkom.it\/eolica-mediterranean-expo-2012\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nesasrl.sp2.netkom.it\/eolica-mediterranean-expo-2012\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nesasrl.sp2.netkom.it\/it\/"},{"@type":"ListItem","position":2,"name":"EOLICA MEDITERRANEAN EXPO 2012"}]},{"@type":"WebSite","@id":"https:\/\/nesasrl.sp2.netkom.it\/#website","url":"https:\/\/nesasrl.sp2.netkom.it\/","name":"Nesa","description":"Sistemi per il monitoraggio ambientale e telecontrollo","publisher":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nesasrl.sp2.netkom.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nesasrl.sp2.netkom.it\/#organization","name":"Nesa srl","url":"https:\/\/nesasrl.sp2.netkom.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/","url":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","contentUrl":"https:\/\/nesasrl.sp2.netkom.it\/wp-content\/uploads\/2021\/11\/logo_nesa_R_250x55.svg","width":264,"height":55,"caption":"Nesa srl"},"image":{"@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/nesa-srl\/","https:\/\/www.facebook.com\/nesasrl"]},{"@type":"Person","@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/person\/f04f829b25d9803bd3039afd4b37395a","name":"moris","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nesasrl.sp2.netkom.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f8a6da1a0980ff05aa322b98cbd1907117e072e21dd674cbce479e811160e614?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f8a6da1a0980ff05aa322b98cbd1907117e072e21dd674cbce479e811160e614?s=96&d=mm&r=g","caption":"moris"},"sameAs":["https:\/\/nesasrl.sp2.netkom.it\/","https:\/\/twitter.com\/moris"]}]}},"_links":{"self":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/en\/wp-json\/wp\/v2\/posts\/3554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/en\/wp-json\/wp\/v2\/comments?post=3554"}],"version-history":[{"count":1,"href":"https:\/\/nesasrl.sp2.netkom.it\/en\/wp-json\/wp\/v2\/posts\/3554\/revisions"}],"predecessor-version":[{"id":3559,"href":"https:\/\/nesasrl.sp2.netkom.it\/en\/wp-json\/wp\/v2\/posts\/3554\/revisions\/3559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/en\/wp-json\/wp\/v2\/media\/3557"}],"wp:attachment":[{"href":"https:\/\/nesasrl.sp2.netkom.it\/en\/wp-json\/wp\/v2\/media?parent=3554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/en\/wp-json\/wp\/v2\/categories?post=3554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nesasrl.sp2.netkom.it\/en\/wp-json\/wp\/v2\/tags?post=3554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}